{"id":81832,"date":"2026-09-02T11:47:49","date_gmt":"2026-09-02T14:47:49","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=81832"},"modified":"2026-09-02T11:47:52","modified_gmt":"2026-09-02T14:47:52","slug":"projeto-um-dia-para-sonhar-e-apresentado-a-alunos-do-colegio-zelia-ceranto-rivatto-em-pontal-do-parana","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2026\/09\/02\/projeto-um-dia-para-sonhar-e-apresentado-a-alunos-do-colegio-zelia-ceranto-rivatto-em-pontal-do-parana\/","title":{"rendered":"Projeto \u201cUm Dia para Sonhar\u201d \u00e9 apresentado a alunos do Col\u00e9gio Z\u00e9lia Ceranto Rivatto em Pontal do Paran\u00e1"},"content":{"rendered":"\n<p>A\u00e7\u00e3o do Rotary e da Secretaria de Educa\u00e7\u00e3o vai selecionar estudantes do 5\u00ba ano para um dia de atividades em outubro<\/p>\n\n\n\n<p>O projeto \u201cUm Dia para Sonhar\u201d foi apresentado nesta ter\u00e7a-feira (1\u00ba) aos alunos e professores do Col\u00e9gio Municipal Z\u00e9lia Ceranto Rivatto, no balne\u00e1rio Primavera, em Pontal do Paran\u00e1. A iniciativa \u00e9 desenvolvida pelo Rotary Club Pontal do Paran\u00e1 Uni\u00e3o em parceria com a Secretaria Municipal de Educa\u00e7\u00e3o (SMED) e prev\u00ea a participa\u00e7\u00e3o de at\u00e9 80 estudantes do 5\u00ba ano da rede municipal em uma programa\u00e7\u00e3o no Hotel Mata Atl\u00e2ntica, no dia 7 de outubro.<\/p>\n\n\n\n<p>Durante a visita, representantes do Rotary, do Hotel Mata Atl\u00e2ntica e da Secretaria Municipal de Educa\u00e7\u00e3o conversaram com os estudantes em sala de aula e apresentaram a proposta da a\u00e7\u00e3o. O encontro tamb\u00e9m serviu para explicar as atividades que ser\u00e3o utilizadas na sele\u00e7\u00e3o dos participantes.<\/p>\n\n\n\n<p>De acordo com o projeto, cada escola poder\u00e1 selecionar at\u00e9 10 estudantes. Entre os crit\u00e9rios est\u00e3o a participa\u00e7\u00e3o em uma atividade de reda\u00e7\u00e3o, a produ\u00e7\u00e3o de um desenho, a assiduidade e atitudes de respeito e companheirismo no ambiente escolar. A proposta busca tamb\u00e9m incentivar a leitura e a escrita, estimular a criatividade, trabalhar valores de cidadania e apresentar aos estudantes o trabalho volunt\u00e1rio desenvolvido pelo Rotary.<\/p>\n\n\n\n<p>A sele\u00e7\u00e3o ser\u00e1 realizada por uma comiss\u00e3o formada por representantes do Rotary, da Secretaria de Educa\u00e7\u00e3o e das escolas participantes. A distribui\u00e7\u00e3o das vagas prev\u00ea modalidades de reda\u00e7\u00e3o, desenho, assiduidade e respeito e companheirismo.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o prevista para o dia 7 de outubro inclui recep\u00e7\u00e3o e caf\u00e9 da manh\u00e3, trilha e atividades recreativas, almo\u00e7o, atividades com recreadores e encerramento no fim da tarde.<\/p>\n\n\n\n<p>A apresenta\u00e7\u00e3o no Col\u00e9gio Z\u00e9lia Ceranto Rivatto iniciou a etapa de visitas \u00e0s escolas participantes. As equipes do Rotary, do Hotel Mata Atl\u00e2ntica e da Secretaria Municipal de Educa\u00e7\u00e3o seguir\u00e3o nas pr\u00f3ximas semanas para as demais unidades da rede, onde tamb\u00e9m ser\u00e3o apresentadas as informa\u00e7\u00f5es sobre o projeto e os crit\u00e9rios de sele\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para ajudar na arrecada\u00e7\u00e3o de recursos para a iniciativa, o Rotary realizar\u00e1 o Jantar Festivo Italiano no dia 19 de setembro, no Restaurante Karranka, em Pontal do Sul. Parte da renda dos convites ser\u00e1 destinada ao projeto. Empres\u00e1rios, comerciantes e moradores tamb\u00e9m podem participar como colaboradores ou patrocinadores da a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Estiveram presentes na visita ao col\u00e9gio o presidente do Rotary Club Pontal do Paran\u00e1 Uni\u00e3o, gest\u00e3o 2026\/2027, Jean Carlo Worell; a diretora administrativa do Rotary, T\u00e2nia B. C. Lugli; a rotariana e representante do Hotel Mata Atl\u00e2ntica, D\u00e9bora P. Ribeiro; o rotariano e representante do Hotel Mata Atl\u00e2ntica, Fredson L. Ribeiro; e a diretora do Col\u00e9gio Z\u00e9lia Ceranto Rivatto, Maria Jos\u00e9.<\/p>\n\n\n\n<p>Fotos: Clovis Santos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o do Rotary e da Secretaria de Educa\u00e7\u00e3o vai selecionar estudantes do 5\u00ba ano para um dia de atividades em outubro O projeto \u201cUm Dia para Sonhar\u201d foi apresentado nesta ter\u00e7a-feira (1\u00ba) aos alunos e professores do Col\u00e9gio Municipal Z\u00e9lia Ceranto Rivatto, no balne\u00e1rio Primavera, em Pontal do Paran\u00e1. A iniciativa \u00e9 desenvolvida pelo Rotary [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":81833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[65],"tags":[],"class_list":{"0":"post-81832","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-pontal-do-parana"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-02-at-11.46.28.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81832"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=81832"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81832\/revisions"}],"predecessor-version":[{"id":81834,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/81832\/revisions\/81834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/81833"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=81832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=81832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=81832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}