{"id":80326,"date":"2026-07-15T13:45:22","date_gmt":"2026-07-15T16:45:22","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=80326"},"modified":"2026-07-15T13:45:25","modified_gmt":"2026-07-15T16:45:25","slug":"obras-de-protecao-apos-incendio-do-instituto-de-educacao-de-paranagua-iniciam-nesta-quinta-feira-16","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2026\/07\/15\/obras-de-protecao-apos-incendio-do-instituto-de-educacao-de-paranagua-iniciam-nesta-quinta-feira-16\/","title":{"rendered":"Obras de prote\u00e7\u00e3o ap\u00f3s inc\u00eandio do Instituto de Educa\u00e7\u00e3o de Paranagu\u00e1 iniciam nesta quinta-feira (16)"},"content":{"rendered":"\n<p>Os trabalhos de limpeza e estabiliza\u00e7\u00e3o estrutural do Instituto de Educa\u00e7\u00e3o Caetano<br>Munhoz da Rocha, em Paranagu\u00e1, iniciam nesta quinta-feira (16). A interven\u00e7\u00e3o marca a<br>primeira etapa da recupera\u00e7\u00e3o do pr\u00e9dio hist\u00f3rico atingido por um inc\u00eandio em abril deste<br>ano.<\/p>\n\n\n\n<p>Os servi\u00e7os incluem o fechamento provis\u00f3rio da \u00e1rea atingida pelo inc\u00eandio, a instala\u00e7\u00e3o de<br>cobertura tempor\u00e1ria para prote\u00e7\u00e3o da estrutura, o travamento e escoramento das paredes<br>remanescentes, al\u00e9m da limpeza e remo\u00e7\u00e3o dos materiais danificados.<br>O objetivo da interven\u00e7\u00e3o \u00e9 garantir a seguran\u00e7a estrutural imediata do edif\u00edcio, evitar a<br>deteriora\u00e7\u00e3o progressiva do patrim\u00f4nio hist\u00f3rico e preparar o im\u00f3vel para as pr\u00f3ximas fases<br>de recupera\u00e7\u00e3o e reconstru\u00e7\u00e3o.<\/p>\n\n\n\n<p>Segundo o chefe do N\u00facleo Regional de Educa\u00e7\u00e3o (NRE) de Paranagu\u00e1, Paulo Penteado,<br>esta \u00e9 uma etapa fundamental da recupera\u00e7\u00e3o do Instituto de Educa\u00e7\u00e3o. \u201cEssa fase \u00e9 muito<br>importante porque representa o in\u00edcio efetivo das a\u00e7\u00f5es de reconstru\u00e7\u00e3o e restauro do<br>Instituto de Educa\u00e7\u00e3o de Paranagu\u00e1. O in\u00edcio da limpeza e da estabiliza\u00e7\u00e3o mostra para<br>toda a comunidade que a recupera\u00e7\u00e3o do instituto j\u00e1 est\u00e1 em andamento, com a\u00e7\u00f5es<br>concretas desenvolvidas passo a passo\u201d.<\/p>\n\n\n\n<p>CHAMAMENTO P\u00daBLICO \u2013 Est\u00e1 aberto um chamamento p\u00fablico para captar<br>patrocinadores interessados em apoiar o projeto de restaura\u00e7\u00e3o e reconstru\u00e7\u00e3o do Instituto<br>de Educa\u00e7\u00e3o de Paranagu\u00e1. O edital prev\u00ea a participa\u00e7\u00e3o de pessoas f\u00edsicas e jur\u00eddicas<br>interessadas em contribuir com a recupera\u00e7\u00e3o do pr\u00e9dio hist\u00f3rico e o prazo para<br>apresenta\u00e7\u00e3o das propostas de patroc\u00ednio segue at\u00e9 30 de julho.<\/p>\n\n\n\n<p>As institui\u00e7\u00f5es interessadas poder\u00e3o oferecer cotas de patroc\u00ednio para a contrata\u00e7\u00e3o de<br>uma consultoria especializada, em tr\u00eas modalidades: mestre, mentor e mecenas, com<br>aportes entre R$ 60 mil e R$ 200 mil. A consultoria ser\u00e1 respons\u00e1vel pelos estudos e pelo<br>acompanhamento t\u00e9cnico de todo o processo de restaura\u00e7\u00e3o. A obra e o restauro do pr\u00e9dio<br>ser\u00e3o executados com recursos p\u00fablicos. O edital tamb\u00e9m foi publicado no Documentador<br>Paran\u00e1 e est\u00e1 dispon\u00edvel para consulta p\u00fablica.<\/p>\n\n\n\n<p>DANOS MATERIAIS &#8211; O inc\u00eandio ocorreu em 4 de abril e atingiu a estrutura do pr\u00e9dio<br>hist\u00f3rico, constru\u00eddo em 1927 e tombado pelo Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico do Paran\u00e1<br>desde 1991. Apesar dos danos materiais, n\u00e3o houve feridos. A unidade atende mais de 1,6<br>mil estudantes e \u00e9 refer\u00eancia na forma\u00e7\u00e3o de docentes e no ensino p\u00fablico.<\/p>\n\n\n\n<p>Logo ap\u00f3s o incidente, foi criada uma for\u00e7a-tarefa envolvendo a Secretaria da Educa\u00e7\u00e3o, o<br>Instituto Paranaense de Desenvolvimento Educacional (Fundepar), o Corpo de Bombeiros e<br>demais \u00f3rg\u00e3os estaduais para avaliar os danos e definir as medidas necess\u00e1rias para a<br>recupera\u00e7\u00e3o da escola. Equipes t\u00e9cnicas da Seed-PR e do Fundepar foram mobilizadas<br>para realizar levantamentos estruturais e elaborar os encaminhamentos para a restaura\u00e7\u00e3o<br>do im\u00f3vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os trabalhos de limpeza e estabiliza\u00e7\u00e3o estrutural do Instituto de Educa\u00e7\u00e3o CaetanoMunhoz da Rocha, em Paranagu\u00e1, iniciam nesta quinta-feira (16). A interven\u00e7\u00e3o marca aprimeira etapa da recupera\u00e7\u00e3o do pr\u00e9dio hist\u00f3rico atingido por um inc\u00eandio em abril desteano. Os servi\u00e7os incluem o fechamento provis\u00f3rio da \u00e1rea atingida pelo inc\u00eandio, a instala\u00e7\u00e3o decobertura tempor\u00e1ria para prote\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[77],"tags":[],"class_list":{"0":"post-80326","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paranagua"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.00.55.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80326"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=80326"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80326\/revisions"}],"predecessor-version":[{"id":80328,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80326\/revisions\/80328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/80327"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=80326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=80326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=80326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}