{"id":75303,"date":"2026-01-04T10:04:14","date_gmt":"2026-01-04T13:04:14","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=75303"},"modified":"2026-01-04T10:04:16","modified_gmt":"2026-01-04T13:04:16","slug":"para-toda-a-familia-arena-gamer-une-tecnologia-diversao-e-solidariedade-em-caioba","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2026\/01\/04\/para-toda-a-familia-arena-gamer-une-tecnologia-diversao-e-solidariedade-em-caioba\/","title":{"rendered":"Para toda a fam\u00edlia: Arena Gamer une tecnologia, divers\u00e3o e solidariedade em Caiob\u00e1"},"content":{"rendered":"\n<p>At\u00e9 1\u00ba de fevereiro, o p\u00fablico de todas as idades pode aproveitar mais uma atra\u00e7\u00e3o para moradores e veranistas na praia de Caiob\u00e1, em Matinhos. \u00c9 a Arena Gamer, que integra a programa\u00e7\u00e3o oficial do Ver\u00e3o Maior Paran\u00e1 e transforma o balne\u00e1rio em um ponto de encontro que une tecnologia e entretenimento.<\/p>\n\n\n\n<p>A iniciativa \u00e9 da Federa\u00e7\u00e3o Paranaense de Esports (FPE), com apoio do Governo do Estado do Paran\u00e1, por meio da Secretaria do Esporte (SEES).\u00a0Conta com o patroc\u00ednio do Viaje Paran\u00e1 e da Line Internet, al\u00e9m do apoio da TL Games.<\/p>\n\n\n\n<p>A Arena oferece dezenas de consoles e centenas de jogos, que v\u00e3o de lan\u00e7amentos atuais a cl\u00e1ssicos que marcaram gera\u00e7\u00f5es. O espa\u00e7o foi planejado para atender p\u00fablicos de todas as idades, desde crian\u00e7as e fam\u00edlias at\u00e9 jogadores experientes e pessoas que nunca tiveram contato com videogames ou com os esportes eletr\u00f4nicos.<\/p>\n\n\n\n<p>O local funciona das 15h \u00e0s 20h, no Posto Caiob\u00e1. Para ter acesso basta levar um quilo de alimento n\u00e3o perec\u00edvel, um item de higiene pessoal ou um brinquedo em bom estado. A expectativa \u00e9 atender mais de 5 mil turistas e moradores locais e arrecadar cerca de 1,5 tonelada de alimentos no per\u00edodo para entidades sociais da cidade. As atividades iniciaram em 28 de dezembro.<\/p>\n\n\n\n<p>\u201cEstamos movimentando o p\u00fablico dos esportes intelectivos, reunindo diferentes jogos e plataformas em um mesmo espa\u00e7o. Todos est\u00e3o convidados a prestigiar a Arena Gamer. Al\u00e9m de muita atividade f\u00edsica, esportiva e criativa, o p\u00fablico tamb\u00e9m encontra atividades intelectuais e tecnologia\u201d, afirma Tiago Campos, diretor de Inova\u00e7\u00e3o e Desenvolvimento da SEES.<\/p>\n\n\n\n<p>\u201cA Federa\u00e7\u00e3o de Esports tem orgulho em trazer aos veranistas a nossa Arena Gamer em mais uma edi\u00e7\u00e3o do Ver\u00e3o Maior Paran\u00e1. Nesta edi\u00e7\u00e3o, contamos com consoles da fam\u00edlia PlayStation, jogos interativos de Xbox, como Just Dance e t\u00edtulos esportivos, al\u00e9m de um simulador de corrida que tem sido um dos destaques entre os participantes\u201d, destaca o Federa\u00e7\u00e3o Paranaense de Esports, Diego Pereira.<\/p>\n\n\n\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n\n\n\n<p>Arena Gamer<\/p>\n\n\n\n<p>Hor\u00e1rio: das 15h \u00e0s 20h<\/p>\n\n\n\n<p>Local: Avenida Atl\u00e2ntica, entre as ruas Apucarana, Paranagu\u00e1 e Ponta Grossa \u2013 Caiob\u00e1<\/p>\n\n\n\n<p>Acesso com a entrega de 1 quilo de alimento n\u00e3o perec\u00edvel, um item de higiene pessoal ou um brinquedo em bom estado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 1\u00ba de fevereiro, o p\u00fablico de todas as idades pode aproveitar mais uma atra\u00e7\u00e3o para moradores e veranistas na praia de Caiob\u00e1, em Matinhos. \u00c9 a Arena Gamer, que integra a programa\u00e7\u00e3o oficial do Ver\u00e3o Maior Paran\u00e1 e transforma o balne\u00e1rio em um ponto de encontro que une tecnologia e entretenimento. A iniciativa \u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":75304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40,1545],"tags":[316],"class_list":{"0":"post-75303","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques","8":"category-verao-maior","9":"tag-litoral"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2026\/01\/img_3984.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75303"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=75303"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75303\/revisions"}],"predecessor-version":[{"id":75305,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/75303\/revisions\/75305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/75304"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=75303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=75303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=75303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}