{"id":67340,"date":"2025-05-21T18:21:08","date_gmt":"2025-05-21T21:21:08","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=67340"},"modified":"2025-05-21T18:21:11","modified_gmt":"2025-05-21T21:21:11","slug":"brde-labs-parana-lanca-edital-para-startups-solucionarem-desafios-em-ia","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2025\/05\/21\/brde-labs-parana-lanca-edital-para-startups-solucionarem-desafios-em-ia\/","title":{"rendered":"BRDE Labs Paran\u00e1 lan\u00e7a edital para startups solucionarem desafios em IA"},"content":{"rendered":"\n<p>O BRDE Labs Paran\u00e1, programa de inova\u00e7\u00e3o do Banco Regional de Desenvolvimento do Extremo Sul (BRDE), reuniu nesta quarta-feira (21) as dez empresas paranaenses que participam do programa como \u00e2ncoras para apresentarem seus desafios reais de inova\u00e7\u00e3o, focados em Intelig\u00eancia Artificial (IA). Nesta edi\u00e7\u00e3o, as empresas que prop\u00f5em os desafios s\u00e3o a 3L Bike Parts, Atlas Eletrodom\u00e9sticos, Bree, Brose, C.Vale, Grupo Gondaski, Horse, Lojas MM, MGL Mec\u00e2nica de Precis\u00e3o e Millpar.<\/p>\n\n\n\n<p>No mesmo encontro, foi lan\u00e7ado o edital que abriu as inscri\u00e7\u00f5es para startups interessadas em participar como solucionadoras dos desafios das empresas. O prazo \u00e9 at\u00e9 7 de julho.<\/p>\n\n\n\n<p>O evento aconteceu no Innosphera Meeting Center, espa\u00e7o de conex\u00f5es da Hotmilk, ecossistema de inova\u00e7\u00e3o da Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1, que atua como parceira do BRDE na iniciativa. Os desafios e o edital para o programa podem ser acessados no site&nbsp;<strong><a href=\"https:\/\/www.brdelabs.com.br\/desafios-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.brdelabs.com.br\/desafios-2025\/<\/a><\/strong>.<\/p>\n\n\n\n<p>O BRDE \u00e9 um dos principais intermediadores de recursos para a inova\u00e7\u00e3o no pa\u00eds, posi\u00e7\u00e3o que refor\u00e7a por meio do programa BRDE Labs. \u201cEsse movimento \u00e9 fundamental para fortalecer o desenvolvimento, a pesquisa e o empreendedorismo inovador. Nosso compromisso ultrapassa o fomento: queremos conectar quem demanda solu\u00e7\u00f5es \u00e0s empresas que as criam\u201d, afirma o diretor administrativo da institui\u00e7\u00e3o, Heraldo Neves.<\/p>\n\n\n\n<p>Marcelo Moura, diretor da Hotmilk PUCPR, explica que o programa oferece a empresas e startups um suporte completo, com apoio t\u00e9cnico e consultoria proporcionados por um ecossistema de inova\u00e7\u00e3o, estimulando aprendizado e desenvolvimento. \u201cA escolha da Intelig\u00eancia Artificial como tema deste ano abre territ\u00f3rios ainda pouco explorados, com enorme potencial de impacto. Essa colabora\u00e7\u00e3o gera benef\u00edcios concretos para as empresas, que passam a ter acesso a solu\u00e7\u00f5es inovadoras capazes de resolver problemas reais do seu dia a dia\u201d, salienta.<\/p>\n\n\n\n<p><strong>FORMATO INOVADOR&nbsp;<\/strong>&#8211; Nesta fase, o programa adotou o formato de pitch reverso, no qual as empresas apresentam seus principais desafios para que as startups identifiquem oportunidades de atua\u00e7\u00e3o e se inscrevam no edital. Podem participar startups com pelo menos seis meses de funda\u00e7\u00e3o que ofere\u00e7am solu\u00e7\u00f5es inovadoras em produtos, servi\u00e7os ou processos.<\/p>\n\n\n\n<p>Finalizado o prazo de inscri\u00e7\u00e3o de startups, o programa ter\u00e1 dura\u00e7\u00e3o de tr\u00eas meses. Ser\u00e3o selecionadas at\u00e9 10 startups por empresa para rodada de pitches online que ser\u00e3o avaliadas pelas empresas participantes. Para a etapa seguinte, ser\u00e3o selecionadas at\u00e9 duas startups por empresa, para um per\u00edodo de imers\u00e3o, a fim de aprofundar a compreens\u00e3o dos desafios.<\/p>\n\n\n\n<p>Ser\u00e1 desenvolvida uma proposta de Prova de Conceito (PoC) \u2013 modelo que demonstra a viabilidade da ideia ou proposta \u2013&nbsp;que poder\u00e1 ser contratada ao final do programa. Al\u00e9m disso, as startups ter\u00e3o acesso \u00e0 Comunidade BRDE Labs Digital, onde poder\u00e3o se conectar com outras institui\u00e7\u00f5es, receber consultorias, participar de workshops e acessar cursos focados em gest\u00e3o e inova\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>EXPECTATIVAS DAS PARTICIPANTES<\/strong>&nbsp;&#8211; Para as empresas que apresentam os desafios, o BRDE Labs representa uma oportunidade estrat\u00e9gica de acelerar a transforma\u00e7\u00e3o digital por meio da colabora\u00e7\u00e3o com startups inovadoras.<\/p>\n\n\n\n<p>O supervisor de S&amp;OP da Millpar, Jackson Gon\u00e7alves, conta que a ind\u00fastria madeireira est\u00e1 participando pela primeira vez do programa e que a expectativa \u00e9 solucionar dois grandes desafios: fazer a gest\u00e3o de estoque em tempo real por meio da IA e a manuten\u00e7\u00e3o preditiva na \u00e1rea de produ\u00e7\u00e3o.&nbsp;\u201cEstamos bastante ansiosos para ouvir as ideias, pois, por estarmos imersos no dia a dia da empresa, muitas vezes nossas perspectivas ficam limitadas. A intera\u00e7\u00e3o com as startups pode trazer insights in\u00e9ditos e at\u00e9 solu\u00e7\u00f5es que nunca consideramos para nossos desafios\u201d, ressalta.<\/p>\n\n\n\n<p>A executiva de vendas da statup Driva, Let\u00edcia Carvalho, contou que esta \u00e9 a segunda participa\u00e7\u00e3o da startup no BRDE Labs Paran\u00e1. Na edi\u00e7\u00e3o anterior, a empresa de tecnologia, que usa dados para auxiliar em vendas, conseguiu implementar duas Provas de Conceito com empresas interessadas em solu\u00e7\u00f5es para mapeamento de mercado.<\/p>\n\n\n\n<p>\u201cEstamos com grandes expectativas para esta edi\u00e7\u00e3o. O formato do pitch reverso nos mostrou diversas oportunidades de apoiar as empresas em seus desafios. Essa din\u00e2mica, em que as pr\u00f3prias empresas apresentam suas demandas faz todo sentido e torna a conex\u00e3o muito mais efetiva,\u201d afirma.<\/p>\n\n\n\n<p>Lan\u00e7ado em 2020, o BRDE Labs tem como objetivo ampliar o ecossistema de inova\u00e7\u00e3o na regi\u00e3o Sul, qualificando startups e conectando-as a empresas de diversos setores que enfrentam desafios internos e buscam solu\u00e7\u00f5es in\u00e9ditas.<\/p>\n\n\n\n<p>Assessoria <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O BRDE Labs Paran\u00e1, programa de inova\u00e7\u00e3o do Banco Regional de Desenvolvimento do Extremo Sul (BRDE), reuniu nesta quarta-feira (21) as dez empresas paranaenses que participam do programa como \u00e2ncoras para apresentarem seus desafios reais de inova\u00e7\u00e3o, focados em Intelig\u00eancia Artificial (IA). Nesta edi\u00e7\u00e3o, as empresas que prop\u00f5em os desafios s\u00e3o a 3L Bike Parts, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[121],"tags":[319],"class_list":{"0":"post-67340","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tecnologia-2","8":"tag-parana"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2025\/05\/20250520_mcharneski_brde_labs_034-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67340"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67340"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67340\/revisions"}],"predecessor-version":[{"id":67342,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67340\/revisions\/67342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/67341"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}