{"id":59226,"date":"2024-06-14T17:14:45","date_gmt":"2024-06-14T20:14:45","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=59226"},"modified":"2024-06-14T17:14:46","modified_gmt":"2024-06-14T20:14:46","slug":"projeto-de-pesquisa-da-uenp-analisa-saude-da-mulher-a-partir-de-dados-do-datasus","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2024\/06\/14\/projeto-de-pesquisa-da-uenp-analisa-saude-da-mulher-a-partir-de-dados-do-datasus\/","title":{"rendered":"Projeto de pesquisa da UENP analisa sa\u00fade da mulher a partir de dados do Datasus"},"content":{"rendered":"\n<p>Pesquisa desenvolvida na Universidade Estadual do Norte do Paran\u00e1 (UENP) analisa indicadores e aspectos epidemiol\u00f3gicos da sa\u00fade de mulheres paranaenses, a partir de dados do Departamento de Inform\u00e1tica do Sistema \u00danico de Sa\u00fade (Datasus). O objetivo \u00e9 contribuir para o desenvolvimento de pol\u00edticas p\u00fablicas voltadas para a qualidade de vida das mulheres e a\u00e7\u00f5es de preven\u00e7\u00e3o, diagn\u00f3stico precoce e tratamento de doen\u00e7as. Os dados s\u00e3o coletados desde 2008.<\/p>\n\n\n\n<p>O estudo tra\u00e7a um panorama dos 399 munic\u00edpios do Paran\u00e1, aglomerados por macrorregi\u00e3o, combinando diferentes informa\u00e7\u00f5es, como idade, cor, escolaridade, situa\u00e7\u00e3o conjugal, renda e local de resid\u00eancia dessa parcela da popula\u00e7\u00e3o. Os indicadores apontam bons resultados em rela\u00e7\u00e3o ao restante do Brasil e sinaliza pontos de melhoria para manter as condi\u00e7\u00f5es favor\u00e1veis para o bem-estar f\u00edsico, mental e emocional das paranaenses.<\/p>\n\n\n\n<p>O levantamento de dados tamb\u00e9m inclui refer\u00eancias sobre as linhas de cuidado das mulheres no per\u00edodo de gesta\u00e7\u00e3o, parto e puerp\u00e9rio (p\u00f3s-parto), inclusive a sa\u00fade dos rec\u00e9m-nascidos. S\u00e3o observados aspectos importantes, como assist\u00eancia m\u00e9dica durante a gravidez e o parto; tuberculose na gesta\u00e7\u00e3o; mortalidade por c\u00e2ncer de colo do \u00fatero e c\u00e2ncer de mama; nascimentos prematuros e mortalidade infantil decorrente de doen\u00e7as gen\u00e9ticas ou anomalias cong\u00eanitas.<\/p>\n\n\n\n<p>Esta mat\u00e9ria faz parte de uma s\u00e9rie de reportagens voltadas para a divulga\u00e7\u00e3o cient\u00edfica e que tem como objetivo promover os resultados de estudos acad\u00eamicos desenvolvidos por pesquisadores, professores e estudantes das sete universidades estaduais do Paran\u00e1.<\/p>\n\n\n\n<p>Os textos s\u00e3o publicados semanalmente com o selo Paran\u00e1 Mais Ci\u00eancia, um programa estrat\u00e9gico do governo, previsto no Plano Plurianual do Estado (PPA), que viabiliza os recursos financeiros do&nbsp;Fundo Paran\u00e1&nbsp;de fomento cient\u00edfico e tecnol\u00f3gico, administrado pela Secretaria da Ci\u00eancia e Tecnologia e Ensino Superior (Seti). A primeira reportagem foi sobre&nbsp;<strong><a href=\"https:\/\/www.aen.pr.gov.br\/Noticia\/Pesquisas-nas-universidades-estaduais-avaliam-mudancas-climaticas-no-Parana\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisas que avaliam as mudan\u00e7as clim\u00e1ticas no Paran\u00e1<\/a><\/strong>.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>AEN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa desenvolvida na Universidade Estadual do Norte do Paran\u00e1 (UENP) analisa indicadores e aspectos epidemiol\u00f3gicos da sa\u00fade de mulheres paranaenses, a partir de dados do Departamento de Inform\u00e1tica do Sistema \u00danico de Sa\u00fade (Datasus). O objetivo \u00e9 contribuir para o desenvolvimento de pol\u00edticas p\u00fablicas voltadas para a qualidade de vida das mulheres e a\u00e7\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":59227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[121],"tags":[],"class_list":{"0":"post-59226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tecnologia-2"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2024\/06\/design_sem_nome_1-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59226"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59226"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59226\/revisions"}],"predecessor-version":[{"id":59228,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59226\/revisions\/59228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/59227"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}