{"id":24347,"date":"2019-12-15T13:05:00","date_gmt":"2019-12-15T16:05:00","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=24347"},"modified":"2019-12-15T13:05:02","modified_gmt":"2019-12-15T16:05:02","slug":"balneario-picarras-inicia-plantio-9-mil-mudas-para-recuperacao-da-restinga-em-sc","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/12\/15\/balneario-picarras-inicia-plantio-9-mil-mudas-para-recuperacao-da-restinga-em-sc\/","title":{"rendered":"Balne\u00e1rio Pi\u00e7arras inicia plantio 9 mil mudas para recupera\u00e7\u00e3o da restinga em SC"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Replantio \u00e9 o maior j\u00e1 realizado no munic\u00edpio e conta com a instala\u00e7\u00e3o de placas educativas em toda a extens\u00e3o da praia para auxiliar na conscientiza\u00e7\u00e3o, visando recuperar a \u00e1rea atingida pela ressaca<\/h4>\n\n\n\n<p>Balne\u00e1rio Pi\u00e7arras iniciou o replantio da restinga ao lado do Molhe Norte, no trecho que foi destru\u00eddo pela ressaca mar\u00edtima do m\u00eas de julho. Ao todo ser\u00e3o plantadas 9 mil mudas de oito plantas nativas, tornando este o maior projeto de reflorestamento da cidade at\u00e9 agora.<\/p>\n\n\n\n<p>O trecho que recebe a recupera\u00e7\u00e3o da restinga compreende uma \u00e1rea de 200 metros de extens\u00e3o e conta com 8 mudas por metro quadrado. Auxiliando na conscientiza\u00e7\u00e3o da preserva\u00e7\u00e3o da restinga, a Funda\u00e7\u00e3o do Meio Ambiente tamb\u00e9m instalou 100 placas educativas sobre a fauna e flora nativa.<\/p>\n\n\n\n<p>As oito esp\u00e9cies plantadas s\u00e3o nativas da regi\u00e3o, sendo elas: Cacto palma (Opuntia monacantha), salsa de praia (Ipomoea pes-caprae), feij\u00e3o de praia (Sophora tomentosa), pitangueira (Eugenia uniflora), feij\u00e3o-da-praia (Canavalia rosea), aroeira (Schinus terebinthifolius), capim de praia (Spartina ciliata) e roset\u00e3o de praia.<\/p>\n\n\n\n<p>&#8220;Este \u00e9 o maior replantio j\u00e1 realizado em Balne\u00e1rio Pi\u00e7arras e com grande densamento, favorecendo um r\u00e1pido desenvolvimento. A expectativa \u00e9 que no in\u00edcio do pr\u00f3ximo inverno, quando exite forte tend\u00eancia de ressacas, a vegeta\u00e7\u00e3o da restinga esteja recuperada e contribua com a prote\u00e7\u00e3o da contra a eros\u00e3o costeira, evitando danos a estrutura p\u00fablica&#8221;, explica o Presidente da Funda\u00e7\u00e3o do Meio Ambiente, Marcos Zaleski.<\/p>\n\n\n\n<p>Para auxiliar na preserva\u00e7\u00e3o da restinga, o trecho foi delimitado por palanques de eucalipto e corda para evitar a circula\u00e7\u00e3o de pessoas na \u00e1rea replantada, mantendo abertos, apenas os acessos a praia. Outra a\u00e7\u00e3o que auxilia na conscientiza\u00e7\u00e3o para a preserva\u00e7\u00e3o da restinga \u00e9 a instala\u00e7\u00e3o de placas educativas sobre a fauna e flora nativa em toda a extens\u00e3o da praia.<\/p>\n\n\n\n<p>&#8220;Toda a extens\u00e3o da avenida beira-mar e as rampas de acesso \u00e0 praia receberam placas que apresentam aos moradores e turistas os benef\u00edcios de cada esp\u00e9cie nativa e a import\u00e2ncia delas para a preserva\u00e7\u00e3o da orla de Balne\u00e1rio Pi\u00e7arras&#8221;, conta Marcos.<\/p>\n\n\n\n<p>As medidas fazem parte do projeto &#8220;Restinga Preservada, Nossa Praia Protegida&#8221;, uma iniciativa que busca a preserva\u00e7\u00e3o da vegeta\u00e7\u00e3o por meio de a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e preserva\u00e7\u00e3o, replantio, materiais gr\u00e1ficos e placas indicativas na praia.<\/p>\n\n\n\n<p>Adjorisc<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Replantio \u00e9 o maior j\u00e1 realizado no munic\u00edpio e conta com a instala\u00e7\u00e3o de placas educativas em toda a extens\u00e3o da praia para auxiliar na conscientiza\u00e7\u00e3o, visando recuperar a \u00e1rea atingida pela ressaca Balne\u00e1rio Pi\u00e7arras iniciou o replantio da restinga ao lado do Molhe Norte, no trecho que foi destru\u00eddo pela ressaca mar\u00edtima do m\u00eas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-24347","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/12\/15762638582200.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24347"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=24347"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24347\/revisions"}],"predecessor-version":[{"id":24349,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24347\/revisions\/24349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/24348"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=24347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=24347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=24347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}