{"id":23083,"date":"2019-11-13T10:45:23","date_gmt":"2019-11-13T13:45:23","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=23083"},"modified":"2019-11-13T10:45:26","modified_gmt":"2019-11-13T13:45:26","slug":"contribuintes-deixam-de-resgatar-quase-1-3-do-credito-no-nota-parana","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/11\/13\/contribuintes-deixam-de-resgatar-quase-1-3-do-credito-no-nota-parana\/","title":{"rendered":"Contribuintes deixam de resgatar quase 1\/3 do cr\u00e9dito no Nota Paran\u00e1"},"content":{"rendered":"\n<p>O Nota Paran\u00e1, programa de est\u00edmulo \u00e0 cidadania fiscal no estado do Paran\u00e1, tem por objetivo incentivar os consumidores a exigirem a troca do documento fiscal e, em compensa\u00e7\u00e3o, devolve 30% do imposto recolhido pelos lojistas aos contribuintes. Seu lema, inclusive, \u00e9 \u201cCPF na nota \u00e9 dinheiro de volta\u201d. Mas ainda \u00e9 grandioso o n\u00famero de pessoas que esquecem (ou n\u00e3o querem) resgatar os valores aos quais t\u00eam direito pelo programa.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es da Secretaria de Estado da Fazenda , entre novembro 2015 e julho deste ano o Nota Paran\u00e1 disponibilizou R$ 1,492 bilh\u00e3o aos contribuintes cadastrados no programa. Desse montante, por\u00e9m, R$ 478 milh\u00f5es nunca foram resgatados e acabaram cancelados \u2014 os cr\u00e9ditos vencem a cada 12 meses, contado a partir da data em que tiver sido disponibilizado pela Secretaria da Fazenda. O valor representa cerca de 32% do montante devolvido pelo Estado aos contribuintes.<\/p>\n\n\n\n<p>O resgate dos cr\u00e9ditos gerados pelo programa pode ser feito via dep\u00f3sito em conta corrente ou poupan\u00e7a e tamb\u00e9m pode ser direcionado para o pagamento do IPVA. Para consultar o seu saldo de cr\u00e9ditos dispon\u00edveis, basta acessar a sua conta atrav\u00e9s do Portal da Nota Paran\u00e1, mediante login e senha cadastrada no pr\u00f3prio portal (notaparana.pr.gov.br).<\/p>\n\n\n\n<p>Coordenadora do Nota Paran\u00e1, Marta Gambini aponta que h\u00e1 dois motivos principais para os usu\u00e1rios n\u00e3o resgatarem o cr\u00e9dito a que tem direito. Um deles \u00e9 que compras feitas pela internet incluem automaticamente o CPF do comprador, mas muitas vezes ele n\u00e3o sabe que a empresa do Paran\u00e1 ou desconhece o programa de combate \u00e0 sonega\u00e7\u00e3o fiscal. A dica, ent\u00e3o, \u00e9 olhar o endere\u00e7o do emitente quando a nota fiscal \u00e9 entregue, junto com o produto.<\/p>\n\n\n\n<p>Por outro lado, h\u00e1 ainda muitos paranaense que nem desconfiam que t\u00eam dinheiro para receber e outros que, por pregui\u00e7a ou desconfian\u00e7a, deixam de aproveitar os benef\u00edcios ofertados pelo programa de cidadania fiscal. Para esses, uma solu\u00e7\u00e3o seria doar as notas fiscais para uma entidade social, o que pode ser feito com o dep\u00f3sito da notinha (mesmo que sem o CPF) em urnas espalhas em todo o tipo de estabelecimento. Esse dinheiro, ent\u00e3o, ser\u00e1 direcionado para alguma entidade social usar em seus projetos.<\/p>\n\n\n\n<p><strong>Mitos e verdades sobre o Nota Paran\u00e1<\/strong><br><strong>Para ganhar cr\u00e9ditos, n\u00e3o preciso nem estar cadastrado.<\/strong><br><strong>Verdade \u2014<\/strong>\u00a0Para gerar cr\u00e9ditos, basta informar o seu CPF ou CNPJ no ato da compra. Por\u00e9m, para consultar e utilizar os seus cr\u00e9ditos, bem como para participar dos sorteios mensais, voc\u00ea, consumidor, dever\u00e1 acessar o site do Programa, www.notaparana.pr.gov.br, e efetuar seu cadastro.<br><br><strong>S\u00f3 pode participar quem mora no Paran\u00e1<\/strong><br><strong>Mito \u2014<\/strong>\u00a0Todos os cidad\u00e3os que possuem CPF no territ\u00f3rio nacional podem se cadastrar e receber\u00e3o cr\u00e9dito, inclusive, por algumas compras feitas via internet. J\u00e1 s\u00e3o mais de 4 mil cidades cadastradas no Paran\u00e1, de pessoas que compram de empresas paranaenses.<br><br><strong>Posso ser v\u00edtima de fraude ao informar meu CPF a estabelecimentos comerciais<\/strong><br><strong>Mito \u2014<\/strong>\u00a0Apenas com essa informa\u00e7\u00e3o \u00e9 imposs\u00edvel que algu\u00e9m se torne v\u00edtima de fraude. Ou seja, pode informar tranquilamente seu CPF que n\u00e3o h\u00e1 risco.<br><br><strong>Ao colocar o CPF na nota, o cidad\u00e3o pode cair nas malhas da Receita Federal<\/strong><br><strong>Mito \u2014<\/strong>\u00a0Al\u00e9m do programa de cidadania fiscal n\u00e3o querer saber o quanto a pessoa ganha ou gasta, o Nota Paran\u00e1 \u00e9 gerenciado pelo Governo do Estado, enquanto a Receita Federal (como o pr\u00f3prio nome indica) \u00e9 federal<br><br><strong>Quanto mais notas, mais chances no sorteio<\/strong><br><strong>Verdade \u2014<\/strong>\u00a0A 1\u00aa nota fiscal emitida em cada per\u00edodo de sorteio ir\u00e1 lhe gerar um bilhete Depois disso, voc\u00ea receber\u00e1 mais um bilhete para cada R$ 50 em compras.<br><br><strong>Caso n\u00e3o inclua o CPF no ato da compra, posso cadastrar a nota posteriormente<\/strong><br><strong>Mito \u2014<\/strong>\u00a0O CPF na nota \u00e9 colocado apenas no momento da emiss\u00e3o da mesma.<br><br><strong>O Nota Paran\u00e1 combate sonega\u00e7\u00e3o fiscal e isso \u00e9 bom para o consumidor<\/strong><br><strong>Verdade \u2014<\/strong>\u00a0O combate \u00e0 sonega\u00e7\u00e3o fiscal n\u00e3o s\u00f3 ajuda a aumentar a arrecada\u00e7\u00e3o do Estado, garantindo mais dinheiro para investimentos, como tamb\u00e9m ajuda a reduzir a concorr\u00eancia desleal.<br><br><strong>N\u00e3o vale a pena participar do programa porque o valor restitu\u00eddo \u00e9 pequeno<\/strong><br><strong>Mito \u2014<\/strong>\u00a0Principalmente porque o consumidor n\u00e3o tem nada a perder ao se inscrever no programa e pedir CPF nas notas, al\u00e9m do fato de que exigir o comprovante fiscal \u00e9 um exerc\u00edcio de cidadania. Nos sorteios mensais h\u00e1 a chance de conseguir pr\u00eamios polpudos, de at\u00e9 R$ 50 mil (em datas especiais, o valor chega a R$ 200 mil).<\/p>\n\n\n\n<p>Bem Paran\u00e1<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Nota Paran\u00e1, programa de est\u00edmulo \u00e0 cidadania fiscal no estado do Paran\u00e1, tem por objetivo incentivar os consumidores a exigirem a troca do documento fiscal e, em compensa\u00e7\u00e3o, devolve 30% do imposto recolhido pelos lojistas aos contribuintes. Seu lema, inclusive, \u00e9 \u201cCPF na nota \u00e9 dinheiro de volta\u201d. Mas ainda \u00e9 grandioso o n\u00famero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-23083","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/11\/cpf.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23083"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23083"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23083\/revisions"}],"predecessor-version":[{"id":23085,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23083\/revisions\/23085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/23084"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}