{"id":23070,"date":"2019-11-13T10:10:37","date_gmt":"2019-11-13T13:10:37","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=23070"},"modified":"2019-11-13T10:10:40","modified_gmt":"2019-11-13T13:10:40","slug":"concurso-publico-vai-contratar-147-pessoas-para-trabalhar-no-hospital-de-clinicas","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/11\/13\/concurso-publico-vai-contratar-147-pessoas-para-trabalhar-no-hospital-de-clinicas\/","title":{"rendered":"Concurso p\u00fablico vai contratar 147 pessoas para trabalhar no Hospital de Cl\u00ednicas"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Inscri\u00e7\u00f5es podem ser feitas at\u00e9 10 de dezembro pela internet. H\u00e1 vagas para as \u00e1reas m\u00e9dica, assistencial e administrativa.<\/h4>\n\n\n\n<p>A Empresa Brasileira de Servi\u00e7os Hospitalares (Ebserh) vai contratar 147 pessoas para o Hospital de Cl\u00ednicas (HC) de Curitiba, da Universidade Federal do Paran\u00e1 (UFPR).<\/p>\n\n\n\n<p>H\u00e1 vagas para as \u00e1reas m\u00e9dica, assistencial e administrativa.&nbsp;<a href=\"https:\/\/www.ibfc.org.br\/concurso\/concurso_selecionado\/360\" target=\"_blank\" rel=\"noreferrer noopener\">Confira o edital.<\/a><\/p>\n\n\n\n<p>As provas ser\u00e3o em 2 de fevereiro. Em todo o pa\u00eds,\u00a0s\u00e3o 2.464 vagas\u00a0na rede de hospitais universit\u00e1rios federais. Vinculada ao Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), a Ebserh administra atualmente 40 hospitais universit\u00e1rios federais.<\/p>\n\n\n\n<p>Para Curitiba, al\u00e9m das 147 vagas, h\u00e1 tamb\u00e9m cadastro para reserva.\u00a0As inscri\u00e7\u00f5es podem ser feitas at\u00e9 10 de dezembro pela internet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Taxa de inscri\u00e7\u00e3o<\/h2>\n\n\n\n<p>A taxa de inscri\u00e7\u00e3o tem diferentes pre\u00e7os:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Cargos de n\u00edvel m\u00e9dio\/t\u00e9cnico \u2013 R$ 80<\/li><li>Cargos de n\u00edvel superior das \u00e1reas administrativas e assistenciais \u2013 R$ 180<\/li><li>M\u00e9dicos \u2013 R$ 240<\/li><\/ul>\n\n\n\n<p>Para se inscrever, o candidato deve, ap\u00f3s o reenchimento da ficha de inscri\u00e7\u00e3o, imprimir o boleto banc\u00e1rio e pag\u00e1-lo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira os detalhes das vagas por \u00e1rea<\/h2>\n\n\n\n<p><strong>\u00c1rea m\u00e9dica<\/strong><\/p>\n\n\n\n<p>Na \u00e1rea m\u00e9dica, s\u00e3o 45 vagas para 17 especialidades. O cargo com mais vagas \u00e9 o de anestesiologista \u2013 s\u00e3o 10 vagas. A remunera\u00e7\u00e3o chega a R$ 8.647,57<\/p>\n\n\n\n<p><strong>\u00c1rea assistencial<\/strong><\/p>\n\n\n\n<p>Para a \u00e1rea assistencial, s\u00e3o 85 vagas em 14 especialidades e as demais est\u00e3o com cadastro reserva.<\/p>\n\n\n\n<p>A maior parte das vagas vai para os cargos de enfermeiro (20) e t\u00e9cnico em enfermagem (40).<\/p>\n\n\n\n<p>O sal\u00e1rio chega a R$ 6.690,39 para enfermeiro, para 36h semanais. Tamb\u00e9m h\u00e1 vagas para fonoaudi\u00f3logo e t\u00e9cnico em radiologia.<\/p>\n\n\n\n<p><strong>\u00c1rea administrativa<\/strong><\/p>\n\n\n\n<p>A \u00e1rea administrativa tem 17 vagas para cinco cargos, como analista administrativo e contabilidade.<\/p>\n\n\n\n<p>Os sal\u00e1rios variam, chegando at\u00e9 R$ 7.433 para analista de tecnologia da informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>G1PR<br><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es podem ser feitas at\u00e9 10 de dezembro pela internet. H\u00e1 vagas para as \u00e1reas m\u00e9dica, assistencial e administrativa. A Empresa Brasileira de Servi\u00e7os Hospitalares (Ebserh) vai contratar 147 pessoas para o Hospital de Cl\u00ednicas (HC) de Curitiba, da Universidade Federal do Paran\u00e1 (UFPR). H\u00e1 vagas para as \u00e1reas m\u00e9dica, assistencial e administrativa.&nbsp;Confira o edital. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-23070","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/11\/hcli.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23070"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23070"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23070\/revisions"}],"predecessor-version":[{"id":23072,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23070\/revisions\/23072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/23071"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}