{"id":21715,"date":"2019-10-21T13:53:17","date_gmt":"2019-10-21T16:53:17","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21715"},"modified":"2019-10-21T13:53:18","modified_gmt":"2019-10-21T16:53:18","slug":"protesto-na-praca-de-pedagio-de-jataizinho-termina-com-confusao-entre-manifestantes-e-policiais","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/21\/protesto-na-praca-de-pedagio-de-jataizinho-termina-com-confusao-entre-manifestantes-e-policiais\/","title":{"rendered":"Protesto na pra\u00e7a de ped\u00e1gio de Jataizinho termina com confus\u00e3o entre manifestantes e policiais"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">PM diz que alguns manifestantes atiraram pedras contra equipes da Pol\u00edcia Rodovi\u00e1ria Federal no domingo (20). Esse foi o terceiro protesto realizado na pra\u00e7a de ped\u00e1gio.<\/h4>\n\n\n\n<p>Terminou em confus\u00e3o um protesto realizado no ped\u00e1gio de Jataizinho, na BR-369, no norte do Paran\u00e1, no domingo (20).<\/p>\n\n\n\n<p>Essa foi a terceira manifesta\u00e7\u00e3o realizada na pra\u00e7a de ped\u00e1gio em um m\u00eas. Os manifestantes s\u00e3o contra o pre\u00e7o das tarifas cobradas pela concession\u00e1ria Econorte e contra a instala\u00e7\u00e3o de cancelas antes das cabines de cobran\u00e7a. O valor do ped\u00e1gio para carros \u00e9 de R$ 23,70, o mais caro do estado.<\/p>\n\n\n\n<p>Os manifestantes disseram que a pol\u00edcia soltou bombas durante o protesto e que algumas pessoas ficaram feridas.<\/p>\n\n\n\n<p>Mas, de acordo com a Pol\u00edcia Rodovi\u00e1ria Federal (PRF), os manifestantes bloquearam a rodovia, impediram o tr\u00e2nsito de ve\u00edculo e atiraram pedras contra os policiais que acompanhavam o protesto.<\/p>\n\n\n\n<p>A Econorte conseguiu uma liminar na Justi\u00e7a pedindo a reintegra\u00e7\u00e3o de posse da pra\u00e7a. A Justi\u00e7a de Ibipor\u00e3 determinou que a pol\u00edcia estivesse no local para manter o car\u00e1ter pac\u00edfico da manifesta\u00e7\u00e3o.<\/p>\n\n\n\n<p>A PM informou que policiais do choque foram at\u00e9 o local e, para conter a confus\u00e3o, atiraram bombas de efeito moral.<\/p>\n\n\n\n<p>O comandante do 5\u00b0 Batalh\u00e3o da Pol\u00edcia Militar em Londrina Major Nelson Villa, diz que os policiais agiram muni\u00e7\u00e3o n\u00e3o letal porque pedras foram atiradas contra a equipe da PRF.<\/p>\n\n\n\n<p>\u201cPoucas pessoas que estavam na manifesta\u00e7\u00e3o tentaram depredar o patrim\u00f4nio e a guarni\u00e7\u00e3o da PRF. Os policiais agiram com base na determina\u00e7\u00e3o judicial. Na confus\u00e3o, essas pessoas colocaram fogo na estrada o que complicou ainda mais o tr\u00e2nsito. \u00c9 importante ressaltar que a pol\u00edcia apoia manifesta\u00e7\u00f5es democr\u00e1ticas, os \u00faltimos dois protestos ocorreram sem qualquer problema\u201d, destacou o major.<\/p>\n\n\n\n<p>G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PM diz que alguns manifestantes atiraram pedras contra equipes da Pol\u00edcia Rodovi\u00e1ria Federal no domingo (20). Esse foi o terceiro protesto realizado na pra\u00e7a de ped\u00e1gio. Terminou em confus\u00e3o um protesto realizado no ped\u00e1gio de Jataizinho, na BR-369, no norte do Paran\u00e1, no domingo (20). Essa foi a terceira manifesta\u00e7\u00e3o realizada na pra\u00e7a de ped\u00e1gio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-21715","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sem-categoria"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/manifestacao-pedagio.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21715"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21715"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21715\/revisions"}],"predecessor-version":[{"id":21717,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21715\/revisions\/21717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21716"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}