{"id":21672,"date":"2019-10-21T12:32:14","date_gmt":"2019-10-21T15:32:14","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21672"},"modified":"2019-10-21T12:32:15","modified_gmt":"2019-10-21T15:32:15","slug":"ponta-grossa-sera-sede-do-governo-do-estado","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/21\/ponta-grossa-sera-sede-do-governo-do-estado\/","title":{"rendered":"Ponta Grossa ser\u00e1 sede do Governo do Estado"},"content":{"rendered":"\n<p>Ponta Grossa ser\u00e1 a sede do Executivo Estadual nesta semana. A instala\u00e7\u00e3o do governo no principal polo dos Campos Gerais do Paran\u00e1 ocorre na quarta-feira (23), \u00e0s 9 horas, na sede da prefeitura. Durante toda a quarta e quinta-feira (23 e 24), o governador Carlos Massa Ratinho Junior, o vice-governador Darci Piana, secret\u00e1rios de Estado e diretores de empresas e autarquias despachar\u00e3o do Centro de Eventos e do Centro Agropecu\u00e1rio Ayrton Berger.<\/p>\n\n\n\n<p>Nos dois dias, al\u00e9m de atendimentos \u00e0 popula\u00e7\u00e3o, a agenda inclui reuni\u00e3o com lideran\u00e7as do Conselho da Cidade, reuni\u00e3o de secretariado, inaugura\u00e7\u00f5es do Col\u00e9gio Estadual Linda Bacila e do Parque Ecotecnol\u00f3gico, al\u00e9m de encontros com prefeitos e lideran\u00e7as dos Campos Gerais.<\/p>\n\n\n\n<p>A transfer\u00eancia ocorre durante a 41\u00aa edi\u00e7\u00e3o da Exposi\u00e7\u00e3o Feira Agropecu\u00e1ria e Industrial de Ponta Grossa \u2013 EFAPI, evento tradicional da cidade e que acontecer\u00e1 simultaneamente \u00e0 Feira do Paran\u00e1, evento que volta a ser realizado ap\u00f3s 20 anos.<\/p>\n\n\n\n<p><strong>INTERIOR &#8211;<\/strong>&nbsp;\u00c9 a quarta vez neste ano que a sede administrativa do governo estadual \u00e9 levada para o interior. Em fevereiro, o governo foi transferido para Cascavel, no Oeste, durante o Show Rural. Em abril foi a vez de Londrina, no Norte, durante a ExpoLondrina, e em maio Maring\u00e1, paralelamente \u00e0 Expoing\u00e1. A meta \u00e9 atender todas as regi\u00f5es do Estado.<\/p>\n\n\n\n<p>A mudan\u00e7a tempor\u00e1ria \u00e9 uma estrat\u00e9gia do governo para fortalecer o contato com o interior, se aproximando ainda mais das demandas da popula\u00e7\u00e3o das diversas regi\u00f5es do Estado, explicou o governador Ratinho Junior.<\/p>\n\n\n\n<p>\u201cQueremos estar mais pr\u00f3ximos, prestigiar a regi\u00e3o e mobilizar a nossa equipe para tomar decis\u00f5es e resolver os problemas. Agiliza muito todo o processo\u201d, afirmou o governador. \u201cAo concentrar as a\u00e7\u00f5es de governo durante grandes eventos do agroneg\u00f3cio, tamb\u00e9m demonstramos a aten\u00e7\u00e3o ao setor, que \u00e9 essencial para a economia paranaense\u201d, completou.<\/p>\n\n\n\n<p><strong>APOIO \u2013&nbsp;<\/strong>O Governo do Estado estar\u00e1 presente com diversas a\u00e7\u00f5es durante as feiras. A Secretaria de Estado da Agricultura e do Abastecimento, por meio de suas vinculadas, levar\u00e1 uma s\u00e9rie de eventos t\u00e9cnicos e minicursos. Copel, Sanepar e Celepar tamb\u00e9m ter\u00e3o uma programa\u00e7\u00e3o pr\u00f3pria. Haver\u00e1 ainda a\u00e7\u00f5es da Fomento Paran\u00e1, Detran e Compag\u00e1s, al\u00e9m de iniciativas das Secretarias de Estado do Desenvolvimento Sustent\u00e1vel e Turismo, Sa\u00fade, Infraestrutura e Log\u00edstica, Educa\u00e7\u00e3o e Desenvolvimento Urbano e Obras P\u00fablicas.<\/p>\n\n\n\n<p><strong>Box<br>Confira a agenda do governador em Ponta Grossa<\/strong><br><strong>Quarta-feira, 23 de outubro<br>9 horas: Ato de Instala\u00e7\u00e3o do Governo<\/strong><br>Prefeitura de Ponta Grossa<br><strong>10 horas: coletiva de Imprensa<\/strong><br>Parque de Exposi\u00e7\u00e3o<br><strong>10h30: reuni\u00e3o do secretariado<\/strong><br>Parque de Exposi\u00e7\u00e3o<br><strong>14 horas: atendimento dos secret\u00e1rios<\/strong><br>Parque de Exposi\u00e7\u00e3o<br><strong>15h30: inaugura\u00e7\u00e3o do Col\u00e9gio Estadual Linda Bacila<\/strong><br>Rua Lauro de Almeida, 205, Jardim Monte Carlo<br>1<strong>7 horas: Inaugura\u00e7\u00e3o do Parque Ecotecnol\u00f3gico<\/strong><br>Avenida Monteiro Lobato s\/n<br><strong>Quinta-feira, 24 de outubro<br>9h30: Caf\u00e9 da manh\u00e3 com lideran\u00e7as do Conselho da Cidade<\/strong><br>Sebrae<br><strong>10h30: Encontro com prefeitos e lideran\u00e7as dos Campos Gerais<\/strong><br>Parque de Exposi\u00e7\u00e3o<\/p>\n\n\n\n<p>AEN<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ponta Grossa ser\u00e1 a sede do Executivo Estadual nesta semana. A instala\u00e7\u00e3o do governo no principal polo dos Campos Gerais do Paran\u00e1 ocorre na quarta-feira (23), \u00e0s 9 horas, na sede da prefeitura. Durante toda a quarta e quinta-feira (23 e 24), o governador Carlos Massa Ratinho Junior, o vice-governador Darci Piana, secret\u00e1rios de Estado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-21672","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/pontag.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21672"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21672"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21672\/revisions"}],"predecessor-version":[{"id":21674,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21672\/revisions\/21674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21673"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}