{"id":21507,"date":"2019-10-19T13:28:41","date_gmt":"2019-10-19T16:28:41","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21507"},"modified":"2019-10-19T13:28:42","modified_gmt":"2019-10-19T16:28:42","slug":"casa-em-balneario-camboriu-usa-vento-para-gerar-energia","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/19\/casa-em-balneario-camboriu-usa-vento-para-gerar-energia\/","title":{"rendered":"Casa em Balne\u00e1rio Cambori\u00fa usa vento para gerar energia"},"content":{"rendered":"\n<p>Balne\u00e1rio Cambori\u00fa (SC) acaba de receber a primeira resid\u00eancia da cidade abastecida por energia e\u00f3lica, ou seja, com eletricidade gerada atrav\u00e9s dos ventos. O sistema j\u00e1 est\u00e1 operando com homologa\u00e7\u00e3o da Celesc, desde o final de agosto, numa casa do bairro Parque Bandeirantes. A tecnologia instalada \u00e9 capaz de produzir dois mil kWh (quilowatts-hora), gerando uma economia equivalente a R$625 na fatura mensal de energia da unidade consumidora.<\/p>\n\n\n\n<p>A tecnologia produzida na \u00c1sia chegou ao mercado brasileiro oferecendo vantagens. O empres\u00e1rio Sandro Marin, que instalou em sua resid\u00eancia, conta que o sistema ocupa muito menos espa\u00e7o que as placas fotovoltaicas, por exemplo, e n\u00e3o depende da angula\u00e7\u00e3o relacionada ao sol, al\u00e9m de gerar energia durante a noite.<\/p>\n\n\n\n<p>\u201cO Brasil tem uma costa de oito mil quil\u00f4metros e grande potencial para explorar a energia do vento, principalmente no litoral e aqui na regi\u00e3o sul. Apostamos neste sistema de energia limpa de pequena e m\u00e9dia gera\u00e7\u00e3o, a exemplo das torres maiores, que atualmente geram mais energia que a usina hidrel\u00e9trica de Itaipu. Estamos ansiosos pela chegada da primeira fatura de energia para confirmar a economia indicada pelo fabricante\u201d, afirmou Marin.<\/p>\n\n\n\n<p>Outra vantagem do sistema instalado \u00e9 garantir que a energia excedente seja enviada para a rede da distribuidora local. Isso ocorre porque a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) oferece um incentivo para a diversifica\u00e7\u00e3o da matriz energ\u00e9tica brasileira, reduzindo o ICMS.<\/p>\n\n\n\n<p>\u201cA energia gerada \u00e9 contabilizada em kWh no medidor e a fatura representa a diferen\u00e7a entre a gera\u00e7\u00e3o e o consumo da fam\u00edlia. O saldo positivo \u00e9 revertido em cr\u00e9ditos ao consumidor. Assim, al\u00e9m de suprir a demanda dom\u00e9stica e pagar menos pela conta de luz mensal, o usu\u00e1rio ainda acumula cr\u00e9ditos para descontar nas pr\u00f3ximas faturas, com validade de cinco anos\u201d, explica o diretor da Sua Energia, J\u00falio Paz.<\/p>\n\n\n\n<p>Os cr\u00e9ditos acumulados tamb\u00e9m podem ser compartilhados pela mesma operadora em diferentes pontos de consumo, em \u00e2mbito estadual, desde que a fatura seja do mesmo CNPJ ou CPF. Sandro Marin, que tamb\u00e9m \u00e9 diretor na empresa Tek Trade, ir\u00e1 direcionar os cr\u00e9ditos gerados pelo equipamento em sua resid\u00eancia para o seu neg\u00f3cio, localizado em outro bairro da cidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entenda como funciona a tecnologia<\/h2>\n\n\n\n<p>O sistema de aerogerador \u00e9 formado por uma turbina compacta em formato de cata-vento e um inversor, que transforma a energia cont\u00ednua em alternada, permitindo a leitura pela distribuidora local. O equipamento tamb\u00e9m possui um rotor interno que funciona com indu\u00e7\u00e3o eletromagn\u00e9tica. Isso permite que o sistema continue operando por um per\u00edodo maior sem vento, at\u00e9 que receba uma nova rajada.<\/p>\n\n\n\n<p>J\u00falio Paz \u00e9 diretor da empresa Sua Energia, que det\u00e9m exclusividade para a instala\u00e7\u00e3o e comercializa\u00e7\u00e3o do equipamento no Brasil. Ele explica que o inversor deste sistema e\u00f3lico \u00e9 h\u00edbrido, ou seja, tamb\u00e9m \u00e9 compat\u00edvel com o sistema de energia solar permitindo que a gera\u00e7\u00e3o seja ampliada.<\/p>\n\n\n\n<p>\u201cForam sete anos de pesquisa e desenvolvimento passando pela fase de homologa\u00e7\u00e3o do produto, assinaturas de contratos e certifica\u00e7\u00f5es internacionais at\u00e9 chegar na marca pr\u00f3pria para a gera\u00e7\u00e3o de energia e\u00f3lica. A inova\u00e7\u00e3o foi desenvolvida por um fabricante asi\u00e1tico e cedida \u00e0 Sua Energia com exclusividade em todo territ\u00f3rio nacional. A parceria com a importadora Tek Trade visa fomentar o acesso do consumidor e a populariza\u00e7\u00e3o desta tecnologia\u201d, conta Julio Paz.<\/p>\n\n\n\n<p>Al\u00e9m do telhado de casas a turbina do aerogerador tamb\u00e9m pode ser instalada em locais abertos e topos de pr\u00e9dios, onde h\u00e1 significativa quantidade de vento. \u201cEm Balne\u00e1rio Cambori\u00fa, por exemplo, a alta velocidade dos ventos nos topos dos pr\u00e9dios beneficia ainda mais a instala\u00e7\u00e3o desse sistema\u201d, refor\u00e7a Sandro Marin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Retorno de investimento<\/h2>\n\n\n\n<p>O sistema de aerogerador j\u00e1 est\u00e1 \u00e0 venda no pa\u00eds e deve gerar economia a m\u00e9dio e longo prazo. O consumidor pode adquirir o equipamento atrav\u00e9s de financiamento banc\u00e1rio parcelado em at\u00e9 60 vezes, com taxa competitiva. A vida \u00fatil do equipamento \u00e9 estimada em 40 anos. Para um modelo similar ao instalado na resid\u00eancia de Balne\u00e1rio Cambori\u00fa (SC), com gera\u00e7\u00e3o mensal de dois mil kWh (quilowatts-hora), a estimativa de retorno do investimento \u00e9 de tr\u00eas anos.<\/p>\n\n\n\n<p>Ciclo Vivo<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Balne\u00e1rio Cambori\u00fa (SC) acaba de receber a primeira resid\u00eancia da cidade abastecida por energia e\u00f3lica, ou seja, com eletricidade gerada atrav\u00e9s dos ventos. O sistema j\u00e1 est\u00e1 operando com homologa\u00e7\u00e3o da Celesc, desde o final de agosto, numa casa do bairro Parque Bandeirantes. A tecnologia instalada \u00e9 capaz de produzir dois mil kWh (quilowatts-hora), gerando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34],"tags":[],"class_list":{"0":"post-21507","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-meio-ambiente"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/casavento.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21507"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21507"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21507\/revisions"}],"predecessor-version":[{"id":21509,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21507\/revisions\/21509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21508"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}