{"id":21451,"date":"2019-10-18T16:13:40","date_gmt":"2019-10-18T19:13:40","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21451"},"modified":"2019-10-18T16:13:42","modified_gmt":"2019-10-18T19:13:42","slug":"comeca-operacao-para-descongestionar-vias-de-acesso-ao-porto-de-paranagua-veja-como-funciona","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/18\/comeca-operacao-para-descongestionar-vias-de-acesso-ao-porto-de-paranagua-veja-como-funciona\/","title":{"rendered":"Come\u00e7a opera\u00e7\u00e3o para descongestionar vias de acesso ao Porto de Paranagu\u00e1. Veja como funciona"},"content":{"rendered":"\n<p>A empresa Portos do Paran\u00e1 iniciou nesta sexta-feira (18) a Opera\u00e7\u00e3o Cateter para orientar, prevenir e solucionar o problema do estacionamento irregular nas vias de acesso ao porto e aos terminais de armazenagem e movimenta\u00e7\u00e3o de gr\u00e3os e cont\u00eaineres.<\/p>\n\n\n\n<p>A empresa Portos do Paran\u00e1 iniciou nesta sexta-feira (18) uma opera\u00e7\u00e3o para orientar, prevenir e solucionar o problema da obstru\u00e7\u00e3o nas vias de acesso ao Porto de Paranagu\u00e1 e aos terminais de armazenagem e movimenta\u00e7\u00e3o de gr\u00e3os e cont\u00eaineres. Batizada de Opera\u00e7\u00e3o Cateter, a medida \u00e9 educativa e voltada aos caminhoneiros, mas pode levar ao bloqueio do cadastro do ve\u00edculo e restringir o carregamento e descarga dos produtos. A a\u00e7\u00e3o visa acabar com o estacionamento irregular nas ruas e evitar congestionamentos.<\/p>\n\n\n\n<p>Organizada pela Guarda Portu\u00e1ria, a medida emergencial deve durar cerca de dez dias, podendo ser prorrogada. \u201c\u00c9 uma a\u00e7\u00e3o conjunta da Diretoria de Opera\u00e7\u00f5es e da Unidade Administrativa de Seguran\u00e7a Portu\u00e1ria (Uasp), em uma tentativa de melhorar o fluxo de ve\u00edculos e evitar bloqueios no tr\u00e1fego\u201d, disse o diretor-presidente da Portos do Paran\u00e1, Luiz Fernando Garcia.<\/p>\n\n\n\n<p>Ele explica que a Ag\u00eancia Nacional de Transportes Aquavi\u00e1rios (Antaq) \u00e9 respons\u00e1vel pelas san\u00e7\u00f5es cab\u00edveis aos operadores portu\u00e1rios, mas as infra\u00e7\u00f5es de tr\u00e2nsito, dentro da cidade, s\u00e3o de responsabilidade do poder municipal e da Pol\u00edcia Militar. \u201cComo autoridade portu\u00e1ria, temos limites de atua\u00e7\u00e3o, mas procuramos os agentes envolvidos, incluindo as empresas, para que, juntos, possamos acabar com o estacionamento irregular de caminh\u00f5es que gera problemas n\u00e3o apenas para a opera\u00e7\u00e3o do porto, mas para toda a cidade\u201d, completa.<\/p>\n\n\n\n<p>OPERA\u00c7\u00c3O&nbsp;\u2013 De acordo com informa\u00e7\u00f5es da Uasp, a partir desta sexta (18) e pelos pr\u00f3ximos dias, tr\u00eas viaturas e seis guardas portu\u00e1rios far\u00e3o a ronda e estar\u00e3o posicionados em cinco pontos mais cr\u00edticos. Al\u00e9m de orientar os motoristas quanto \u00e0s rotas a serem seguidas, de acordo com a natureza da carga, os guardas registrar\u00e3o boletim de ocorr\u00eancia para provid\u00eancias ao constatarem alguma irregularidade, ou caso os motoristas insistam na infra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Os infratores ter\u00e3o as placas dos caminh\u00f5es anotadas. A situa\u00e7\u00e3o ser\u00e1 registrada com imagens e o boletim de infra\u00e7\u00e3o de tr\u00e2nsito, desobedi\u00eancia ou outra ocorr\u00eancia ir\u00e3o para a chefia da Guarda Portu\u00e1ria, que poder\u00e1 bloquear o ve\u00edculo no sistema de acesso \u00e0 faixa prim\u00e1ria, terminais p\u00fablicos, p\u00e1tios, sistema Carga Online e, no caso dos caminh\u00f5es de cont\u00eaineres, no sistema de acesso do Terminal de Cont\u00eaineres de Paranagu\u00e1 (TCP).<\/p>\n\n\n\n<p>Em car\u00e1ter preventivo, a Opera\u00e7\u00e3o Cateter visa identificar e analisar os locais e as principais causas dos congestionamentos e obstru\u00e7\u00f5es das vias de acesso. \u201cEssas informa\u00e7\u00f5es constatadas in loco servir\u00e3o para que novos procedimentos operacionais e administrativos sejam sugeridos e adotados, interna ou externamente, com a anu\u00eancia dos demais terminais e \u00f3rg\u00e3os fiscalizadores\u201d, explica a Guarda Portu\u00e1ria, em nota.<\/p>\n\n\n\n<p>AVISOS&nbsp;\u2013 Nesta sexta e no s\u00e1bado (18 e 19), os motoristas cadastrados no sistema Carga Online, j\u00e1 aguardando no p\u00e1tio ou em tr\u00e2nsito, receber\u00e3o um SMS com a seguinte mensagem: \u201ccaminh\u00f5es estacionados em locais proibidos, bloqueando vias ou limpando carretas, entrar\u00e3o em restri\u00e7\u00e3o, ficando sem cadastro para nova viagem ao Porto\u201d.<\/p>\n\n\n\n<p>De acordo com o diretor de Opera\u00e7\u00f5es da Portos do Paran\u00e1, Luiz Teixeira da Silva J\u00fanior, al\u00e9m das mensagens, a equipe da diretoria orientou os operadores para atuar na fila do pr\u00f3prio terminal. \u201cCada operador tem essa responsabilidade, sob pena desses bloqueios que ser\u00e3o feitos nos sistemas de carga e descarga\u201d, afirma.<\/p>\n\n\n\n<p>\u201cQuando acontecem os congestionamentos, todos perdem. O usu\u00e1rio n\u00e3o consegue chegar ao destino da sua carga, seja nas moegas dos terminais graneleiros, seja no p\u00e1tio dos cont\u00eaineres. O cidad\u00e3o n\u00e3o consegue transitar e a seguran\u00e7a no tr\u00e2nsito fica comprometida. Estamos fazendo de tudo para minimizar ao m\u00e1ximo os efeitos desta movimenta\u00e7\u00e3o portu\u00e1ria sobre os parnanguaras\u201d, garante Teixeira.<\/p>\n\n\n\n<p><br><strong>Veja os pontos de atua\u00e7\u00e3o da Opera\u00e7\u00e3o Cateter<\/strong><\/p>\n\n\n\n<p>Ponto 1 \u2013 esquina da Avenida Ayrton Senna com a Rua Manoel Bonif\u00e1cio. A\u00e7\u00e3o: orienta\u00e7\u00e3o de tr\u00e2nsito; caminh\u00f5es conteineiros destinados ao TCP, carregados ou vazios, devem seguir pela Rua Manoel Bonif\u00e1cio at\u00e9 a rua Bar\u00e3o do Rio Branco.<\/p>\n\n\n\n<p>Ponto 2 &#8211; esquina da Avenida Ayrton Senna com a Avenida Coronel Jos\u00e9 Lobo. A\u00e7\u00e3o: orienta\u00e7\u00e3o de tr\u00e2nsito e controle de fluxo de ve\u00edculos.<\/p>\n\n\n\n<p>Ponto 3 \u2013 equina da Avenida Coronel Jos\u00e9 Lobo com a Rua Bar\u00e3o do Rio Branco.<br>A\u00e7\u00e3o: orienta\u00e7\u00e3o de tr\u00e2nsito, controle de fluxo de ve\u00edculos, fiscaliza\u00e7\u00e3o e registro de infra\u00e7\u00e3o para elabora\u00e7\u00e3o de Boletim de Ocorr\u00eancia.<\/p>\n\n\n\n<p>Ponto 4 \u2013 final da Rua Bar\u00e3o do Rio Branco com a Avenida Costeira.<br>A\u00e7\u00e3o: orienta\u00e7\u00e3o de tr\u00e2nsito, controle de fluxo de ve\u00edculos, fiscaliza\u00e7\u00e3o e registro de infra\u00e7\u00e3o para elabora\u00e7\u00e3o de Boletim de Ocorr\u00eancia.<\/p>\n\n\n\n<p>Ponto 5 \u2013 Avenida Portu\u00e1ria, em frente ao TCP.<br>A\u00e7\u00e3o: orienta\u00e7\u00e3o de tr\u00e2nsito, controle de fluxo de ve\u00edculos, fiscaliza\u00e7\u00e3o e registro de infra\u00e7\u00e3o para elabora\u00e7\u00e3o de Boletim de Ocorr\u00eancia.<\/p>\n\n\n\n<p>Bem Paran\u00e1<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa Portos do Paran\u00e1 iniciou nesta sexta-feira (18) a Opera\u00e7\u00e3o Cateter para orientar, prevenir e solucionar o problema do estacionamento irregular nas vias de acesso ao porto e aos terminais de armazenagem e movimenta\u00e7\u00e3o de gr\u00e3os e cont\u00eaineres. A empresa Portos do Paran\u00e1 iniciou nesta sexta-feira (18) uma opera\u00e7\u00e3o para orientar, prevenir e solucionar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[42],"tags":[],"class_list":{"0":"post-21451","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cidades"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/ppo.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21451"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21451"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21451\/revisions"}],"predecessor-version":[{"id":21453,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21451\/revisions\/21453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21452"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}