{"id":21259,"date":"2019-10-16T15:47:37","date_gmt":"2019-10-16T18:47:37","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21259"},"modified":"2019-10-16T15:47:38","modified_gmt":"2019-10-16T18:47:38","slug":"governo-pede-r-16-bi-ao-congresso-para-bancar-de-obras-a-carros-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/16\/governo-pede-r-16-bi-ao-congresso-para-bancar-de-obras-a-carros-de-bolsonaro\/","title":{"rendered":"Governo pede R$ 1,6 bi ao Congresso para bancar de obras a carros de Bolsonaro"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">O maior pedido \u00e9 de um cr\u00e9dito suplementar de R$ 691 milh\u00f5es para refor\u00e7ar a\u00e7\u00f5es j\u00e1 previstas no or\u00e7amento de estatais<\/h4>\n\n\n\n<p>O governo enviou nesta ter\u00e7a-feira (15) ao Congresso dez pedidos de abertura de cr\u00e9dito para refor\u00e7ar programas j\u00e1 previstos no Or\u00e7amento ou criar novas a\u00e7\u00f5es. Os pedidos somam R$ 1,6 bilh\u00e3o e bancam de investimentos de estatais a carros da Presid\u00eancia da Rep\u00fablica.<\/p>\n\n\n\n<p>O maior pedido \u00e9 de um cr\u00e9dito suplementar de R$ 691 milh\u00f5es para refor\u00e7ar a\u00e7\u00f5es j\u00e1 previstas no or\u00e7amento de estatais. No BNDES, os recursos v\u00e3o para obras na sede do banco no Rio de Janeiro e, na Petrobras, para opera\u00e7\u00f5es em campos de petr\u00f3leo.\u00a0 O segundo maior montante solicitado soma R$ 561,6 milh\u00f5es e inclui 11 destina\u00e7\u00f5es. Entre elas, est\u00e1 a troca de ve\u00edculos para o presidente Jair Bolsonaro.<br><\/p>\n\n\n\n<p>De acordo com os pedidos enviados ao Congresso, o cr\u00e9dito proposto tem como objetivo viabilizar, entre outras a\u00e7\u00f5es, \u201co custeio de despesas com seguran\u00e7a institucional do presidente, do vice-presidente, de seus familiares, e de outras autoridades, relacionadas a viagens, bem como despesas com material, instala\u00e7\u00f5es e substitui\u00e7\u00e3o de ve\u00edculos devido ao desgaste normal de uso\u201d.<\/p>\n\n\n\n<p>O valor a ser destinado especificamente aos carros n\u00e3o \u00e9 mencionado nos documentos. Ao todo, as a\u00e7\u00f5es para a Presid\u00eancia e Vice-Presid\u00eancia receber\u00e3o R$ 5,3 milh\u00f5es. Os recursos vir\u00e3o do cancelamentos do apoio \u00e0 estrutura\u00e7\u00e3o e desenvolvimento de projetos de concess\u00f5es e parcerias p\u00fablico-privadas.<\/p>\n\n\n\n<p>Do total dos pedidos feitos pelo Executivo ao Congresso, R$ 45,7 milh\u00f5es ter\u00e3o impacto no resultado prim\u00e1rio (que exclui o pagamento da d\u00edvida). O restante vai impactar a despesa financeira ou ser\u00e1 oriundo de remanejamento de recursos de outras a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Exemplo de a\u00e7\u00e3o cancelada \u00e9 a do aporte que o governo faria na Eletrobras para possibilitar a privatiza\u00e7\u00e3o da empresa. A MP (medida provis\u00f3ria) enviada ao governo neste ano para fazer o pagamento n\u00e3o foi aceita pelo Congresso, e o governo desistiu da ideia, conforme antecipou o jornal Folha de S.Paulo.&nbsp; Agora, o plano de privatiza\u00e7\u00e3o da companhia de energia deve passar pela dilui\u00e7\u00e3o da participa\u00e7\u00e3o acion\u00e1ria da Uni\u00e3o.<\/p>\n\n\n\n<p>O montante que iria para a Eletrobras foi redirecionado em maior parte para um aporte na estatal Petr\u00f3leo Brasileiro S\/A (PPSA). A estrutura\u00e7\u00e3o da PPSA, rec\u00e9m-criada, foi uma exig\u00eancia do TCU (Tribunal de Contas da Uni\u00e3o) neste m\u00eas para dar aval ao edital do megaleil\u00e3o da cess\u00e3o onerosa, marcado para o dia 6 de novembro e que pode render \u00e0 Uni\u00e3o at\u00e9 R$ 106 bilh\u00f5es em pagamentos feitos pelas empresas vencedoras (valor que dever\u00e1 ser dividido entre Petrobras, Uni\u00e3o, estados e munic\u00edpios).<\/p>\n\n\n\n<p>Os dez pedidos foram feitos pelo governo nesta ter\u00e7a, \u00faltimo dia permitido pela LDO (Lei de Diretrizes Or\u00e7ament\u00e1rias) para as solicita\u00e7\u00f5es. A limita\u00e7\u00e3o tem como justificativa dar tempo para as an\u00e1lises do Congresso antes do fim do ano. Mas o governo pretende postergar a data. Um projeto de lei j\u00e1 foi enviado pelo Executivo ao Congresso para adiar o prazo para 14 de novembro.<\/p>\n\n\n\n<p>A inten\u00e7\u00e3o do governo com o adiamento \u00e9 ter mais certeza dos recursos dispon\u00edveis ap\u00f3s o leil\u00e3o da cess\u00e3o onerosa, marcado para daqui a cerca de tr\u00eas semanas. Na pr\u00e1tica, o texto enviado pelo governo permitiria a extens\u00e3o do prazo para a abertura de qualquer tipo de cr\u00e9dito suplementar ou especial.<\/p>\n\n\n\n<p>Os recursos oriundos da cess\u00e3o onerosa podem fazer o governo ter recursos em sobra ao fim do ano. A equipe do ministro Paulo Guedes (Economia) tra\u00e7ou diversos cen\u00e1rios para o resultado do leil\u00e3o. Nas contas mais conservadoras, o governo poder\u00e1 obter neste ano R$ 52,5 bilh\u00f5es com o leil\u00e3o, mais R$ 17,5 bilh\u00f5es no pr\u00f3ximo ano.<br>Desse montante conservador estimado para 2019, R$ 33 bilh\u00f5es teriam de ser pagos \u00e0 Petrobras pela pr\u00f3pria revis\u00e3o do contrato.<\/p>\n\n\n\n<p>Restariam R$ 19,5 bilh\u00f5es que ainda teriam de ser divididos com estados e munic\u00edpios. L\u00edquidos, portanto, o governo teria cerca de R$ 13 bilh\u00f5es para uso em outras despesas ou no c\u00e1lculo do resultado prim\u00e1rio de 2019.<br>A extens\u00e3o do prazo para que o governo possa pedir abertura de cr\u00e9ditos tamb\u00e9m pode servir para atender uma demanda de senadores, pr\u00f3ximos a concluir o segundo turno da reforma da Previd\u00eancia.<\/p>\n\n\n\n<p>Uma ala do Senado quer o mesmo tratamento dado a deputados, que devem receber emendas parlamentares como moeda de troca por terem aprovado a restrutura\u00e7\u00e3o nas regras de aposentadoria.<\/p>\n\n\n\n<p>As emendas s\u00e3o forma de destinar recursos para obras em bases eleitorais de congressistas. Para isso, o Pal\u00e1cio do Planalto enviou em agosto um projeto de lei de abertura de cr\u00e9dito. A medida deve liberar R$ 2 bilh\u00f5es em recursos.<\/p>\n\n\n\n<p>BandaB<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O maior pedido \u00e9 de um cr\u00e9dito suplementar de R$ 691 milh\u00f5es para refor\u00e7ar a\u00e7\u00f5es j\u00e1 previstas no or\u00e7amento de estatais O governo enviou nesta ter\u00e7a-feira (15) ao Congresso dez pedidos de abertura de cr\u00e9dito para refor\u00e7ar programas j\u00e1 previstos no Or\u00e7amento ou criar novas a\u00e7\u00f5es. Os pedidos somam R$ 1,6 bilh\u00e3o e bancam de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32],"tags":[],"class_list":{"0":"post-21259","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/bolsonaro-nordeste-768x498.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21259"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21259"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21259\/revisions"}],"predecessor-version":[{"id":21261,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21259\/revisions\/21261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21260"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}