{"id":21222,"date":"2019-10-16T12:37:27","date_gmt":"2019-10-16T15:37:27","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21222"},"modified":"2019-10-16T12:37:29","modified_gmt":"2019-10-16T15:37:29","slug":"caes-coelhos-galinhas-e-outros-animais-sao-resgatados-de-aviario-dono-foi-autuado-por-maus-tratos","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/16\/caes-coelhos-galinhas-e-outros-animais-sao-resgatados-de-aviario-dono-foi-autuado-por-maus-tratos\/","title":{"rendered":"C\u00e3es, coelhos, galinhas e outros animais s\u00e3o resgatados de avi\u00e1rio; dono foi autuado por maus-tratos"},"content":{"rendered":"\n<p>Um avi\u00e1rio, localizado no bairro Piraquara, na Regi\u00e3o Metropolitana de Curitiba, foi interditado na segunda-feira (14), por n\u00e3o ter alvar\u00e1 de funcionamento e nem m\u00e9dico veterin\u00e1rio respons\u00e1vel pelo estabelecimento. Al\u00e9m disso, 167 animais \u2013 de 21 ra\u00e7as de c\u00e3es diferentes &#8211; foram encontrados em situa\u00e7\u00e3o de maus-tratos.<\/p>\n\n\n\n<p>Os cachorros estavam na parte superior do estabelecimento amarrados em correntes. O ambiente estava extremamente sujo, sem \u00e1gua e comida. Expostos a venda estavam oito peixes, 13 camundongos, nove porcos da \u00cdndia, quatro pombas, 51 galos, 33 galinhas, um marreco, 17 coelhos, quatro pintinhos e seis patos.<\/p>\n\n\n\n<p>O propriet\u00e1rio do avi\u00e1rio, um homem de 41 anos, foi conduzido para a delegacia especializada da Pol\u00edcia Civil e autuado por crime de maus-tratos. Se condenado, poder\u00e1 pegar at\u00e9 um ano de pris\u00e3o, al\u00e9m de multa.<\/p>\n\n\n\n<p>Os animais foram concedidos provisoriamente ao suspeito, que ficou como deposit\u00e1rio fiel. Posteriormente todos os animais ser\u00e3o encaminhados a lares tempor\u00e1rios.<\/p>\n\n\n\n<p><em>Colabora\u00e7\u00e3o e foto: Pol\u00edcia Civil<\/em><a href=\"https:\/\/api.whatsapp.com\/send?text=C%C3%A3es,%20coelhos,%20galinhas%20e%20outros%20animais%20s%C3%A3o%20resgatados%20de%20avi%C3%A1rio;%20dono%20foi%20autuado%20por%20maus-tratos%20http:\/\/redemassa.com.br\/\/noticias\/plantao\/caes-coelhos-galinhas-e-outros-animais-sao-resgatados-de-aviario-dono-foi-autu\" target=\"_blank\" rel=\"noreferrer noopener\"><br>\n\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um avi\u00e1rio, localizado no bairro Piraquara, na Regi\u00e3o Metropolitana de Curitiba, foi interditado na segunda-feira (14), por n\u00e3o ter alvar\u00e1 de funcionamento e nem m\u00e9dico veterin\u00e1rio respons\u00e1vel pelo estabelecimento. Al\u00e9m disso, 167 animais \u2013 de 21 ra\u00e7as de c\u00e3es diferentes &#8211; foram encontrados em situa\u00e7\u00e3o de maus-tratos. Os cachorros estavam na parte superior do estabelecimento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33],"tags":[],"class_list":{"0":"post-21222","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policia"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/dogg.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21222"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21222"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21222\/revisions"}],"predecessor-version":[{"id":21224,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21222\/revisions\/21224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21223"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}