{"id":21049,"date":"2019-10-14T15:31:49","date_gmt":"2019-10-14T18:31:49","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=21049"},"modified":"2019-10-14T15:31:51","modified_gmt":"2019-10-14T18:31:51","slug":"seis-morrem-apos-caminhao-despencar-em-ribanceira-na-grande-curitiba","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/10\/14\/seis-morrem-apos-caminhao-despencar-em-ribanceira-na-grande-curitiba\/","title":{"rendered":"Seis morrem ap\u00f3s caminh\u00e3o despencar em ribanceira na Grande Curitiba"},"content":{"rendered":"\n<p>Seis pessoas morreram ap\u00f3s um grave acidente envolvendo um&nbsp;<strong>caminh\u00e3o<\/strong>&nbsp;que caiu em uma&nbsp;<strong>ribanceira<\/strong>&nbsp;na&nbsp;<strong>PR-092<\/strong>, em um trecho entre&nbsp;<strong>Cerro Azul<\/strong>&nbsp;e&nbsp;<strong>Doutor Ulysses<\/strong>, na regi\u00e3o metropolitana de Curitiba, na tarde deste domingo (13). O caminh\u00e3o, que estava com cerca de 30 pessoas na carroceria, despencou de uma altura de aproximadamente 80 metros, em um trecho sinuoso da pista.<\/p>\n\n\n\n<p>Al\u00e9m das seis mortes, outras 24 pessoas ficaram feridas. A sexta v\u00edtima do acidente, identificada como Rosenilda de Oliveira, morreu na madrugada desta segunda-feira (14), no caminho at\u00e9 o hospital.<\/p>\n\n\n\n<p>As outras v\u00edtimas do acidente s\u00e3o&nbsp;Assis Cavalheiro, motorista do caminh\u00e3o; Lucas Cavalheiro, filho de Assis e que era cadeirante. Eneziane Tim\u00f3teo, cunhada de Assis, e Jo\u00e3o Maria Rosner, tamb\u00e9m parente, n\u00e3o resistiram. O Pastor Valdomiro dos Santos tamb\u00e9m n\u00e3o resistiu aos ferimentos.<\/p>\n\n\n\n<p>Segundo Priscila Marconato, secret\u00e1ria de sa\u00fade de Cerro Azul, logo ap\u00f3s o acidente 20 pessoas foram atendidas na casa hospitalar da cidade. \u201cAgradecemos a ajuda das equipes das outras cidades, que vieram nos ajudar prontamente. Vinte pessoas deram entrada no nosso hospital, sendo duas delas em estado grav\u00edssimo.&nbsp;Uma delas infelizmente morreu no percurso at\u00e9 Curitiba\u201d, explicou a secret\u00e1ria. As v\u00edtimas do acidente eram membros de fam\u00edlias que moram na localidade de&nbsp;Barra do Teixeira, divisa entre Cerro Azul e Doutor Ulysses.<\/p>\n\n\n\n<p>Todas as v\u00edtimas fatais do acidente foram encaminhadas ao Instituto M\u00e9dico Legal (IML) de Curitiba.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pra Curitiba<\/h2>\n\n\n\n<p>Os feridos foram encaminhados aos hospitais Evang\u00e9lico Mackenzie, Cajuru e Trabalhador. Entre os feridos h\u00e1 idosos e crian\u00e7as. O Hospital do Trabalhador recebeu oito pessoas, sendo que duas j\u00e1 receberam alta. O Evang\u00e9lico Mackenzie recebeu 10 pacientes, sendo seis deles crian\u00e7as e outros quatro adultos. Um policial que se envolveu em um acidente quando estava indo atender a ocorr\u00eancia foi levado ao Hospital Cajuru com ferimentos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.tribunapr.com.br\/wp-content\/uploads\/sites\/1\/2019\/10\/acicente-ribanceira-540x333.jpg\" alt=\"Caminh\u00e3o estava com cadeiras instaladas na ca\u00e7amba. Foto: Pol\u00edcia Rodovi\u00e1ria Federal (PRE).\" class=\"wp-image-3033239\"\/><figcaption>Caminh\u00e3o estava com cadeiras instaladas na ca\u00e7amba.<\/figcaption><\/figure>\n\n\n\n<p>carroceria<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Transporte irregular<\/h3>\n\n\n\n<p>O acidente ocorreu enquanto as pessoas eram transportadas em uma F-400 de forma improvisada. todos estavam \u2018acomodados\u2019 em bancos instalados na ca\u00e7amba. Segundo a PRE, o motorista do caminh\u00e3o estava com a Carteira Nacional de Habilita\u00e7\u00e3o (CNH) vencida. Al\u00e9m disso, o ve\u00edculo estava com o licenciamento atrasado. \u201cInfelizmente as vezes a gente se depara com essa situa\u00e7\u00e3o que \u00e9 lament\u00e1vel\u201d, completou a secret\u00e1ria.<\/p>\n\n\n\n<p>TribunaPt<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seis pessoas morreram ap\u00f3s um grave acidente envolvendo um&nbsp;caminh\u00e3o&nbsp;que caiu em uma&nbsp;ribanceira&nbsp;na&nbsp;PR-092, em um trecho entre&nbsp;Cerro Azul&nbsp;e&nbsp;Doutor Ulysses, na regi\u00e3o metropolitana de Curitiba, na tarde deste domingo (13). O caminh\u00e3o, que estava com cerca de 30 pessoas na carroceria, despencou de uma altura de aproximadamente 80 metros, em um trecho sinuoso da pista. Al\u00e9m das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[52],"tags":[],"class_list":{"0":"post-21049","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-acidentes"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/10\/acicente-ribanceira-2-970x550.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21049"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21049"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21049\/revisions"}],"predecessor-version":[{"id":21051,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21049\/revisions\/21051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/21050"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}