{"id":19207,"date":"2019-09-09T09:13:50","date_gmt":"2019-09-09T12:13:50","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=19207"},"modified":"2019-09-09T09:13:51","modified_gmt":"2019-09-09T12:13:51","slug":"bolsonaro-desobriga-publicacao-de-editais-de-concursos-e-licitacoes-em-jornais","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/09\/09\/bolsonaro-desobriga-publicacao-de-editais-de-concursos-e-licitacoes-em-jornais\/","title":{"rendered":"Bolsonaro desobriga publica\u00e7\u00e3o de editais de concursos e licita\u00e7\u00f5es em jornais"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Bolsonaro j\u00e1 havia insinuado no in\u00edcio do m\u00eas passado que tomaria a decis\u00e3o<\/h4>\n\n\n\n<p>Depois de desobrigar empresas de publicarem seus balan\u00e7os em jornais de grande circula\u00e7\u00e3o no Pa\u00eds, o presidente Jair Bolsonaro agora resolveu eliminar tamb\u00e9m a exig\u00eancia legal da divulga\u00e7\u00e3o de editais de concursos, licita\u00e7\u00f5es e leil\u00f5es p\u00fablicos em jornais di\u00e1rios. Bolsonaro j\u00e1 havia insinuado no in\u00edcio do m\u00eas passado que tomaria a decis\u00e3o, formalizada nesta segunda-feira, 9, na Medida Provis\u00f3ria 896\/2019, publicada no Di\u00e1rio Oficial da Uni\u00e3o (DOU).<\/p>\n\n\n\n<p>A MP altera quatro leis, incluindo a Lei de Licita\u00e7\u00f5es e a que regula as parcerias p\u00fablico-privadas, para dispor sobre a forma de publica\u00e7\u00e3o dos atos da administra\u00e7\u00e3o p\u00fablica. Com a MP, os \u00f3rg\u00e3os federais poder\u00e3o divulgar avisos, editais, registro cadastral, extratos, minutas e outros documentos relacionados \u00e0s concorr\u00eancias p\u00fablicas apenas na internet e, em alguns casos, no di\u00e1rio de imprensa oficial dos governos.<\/p>\n\n\n\n<p>\u201cA exig\u00eancia legal de publica\u00e7\u00e3o pela administra\u00e7\u00e3o p\u00fablica federal de seus atos em jornais impressos considera-se atendida com a publica\u00e7\u00e3o dos referidos atos em s\u00edtio eletr\u00f4nico oficial e no Di\u00e1rio Oficial da Uni\u00e3o\u201d, diz um trecho da MP.<\/p>\n\n\n\n<p>Em agosto, Bolsonaro editou uma outra Medida Provis\u00f3ria, a de n\u00famero 892, que permitiu que as publica\u00e7\u00f5es obrigat\u00f3rias de empresas de capital aberto previstas na Lei das S.A, como balan\u00e7os, sejam divulgadas apenas nos sites da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM) e da entidade administradora do mercado em que os valores mobili\u00e1rios da companhia estiverem admitidas \u00e0 negocia\u00e7\u00e3o, como a B3, al\u00e9m do pr\u00f3prio endere\u00e7o eletr\u00f4nico.<\/p>\n\n\n\n<p>Antes, a legisla\u00e7\u00e3o determinava que esses documentos fossem divulgados no \u00f3rg\u00e3o oficial da Uni\u00e3o, Estado ou Distrito Federal, como di\u00e1rios oficiais, conforme o lugar em que a companhia estivesse situada, e em outro jornal de grande circula\u00e7\u00e3o editado na localidade da sede da empresa. As disposi\u00e7\u00f5es da medida provis\u00f3ria j\u00e1 est\u00e3o em vigor, mas s\u00f3 produzir\u00e3o efeitos no primeiro dia do m\u00eas seguinte \u00e0 data de publica\u00e7\u00e3o dos atos da CVM e do Minist\u00e9rio da Economia.<\/p>\n\n\n\n<p>BandaB<br><\/p>\n\n\n\n<p><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolsonaro j\u00e1 havia insinuado no in\u00edcio do m\u00eas passado que tomaria a decis\u00e3o Depois de desobrigar empresas de publicarem seus balan\u00e7os em jornais de grande circula\u00e7\u00e3o no Pa\u00eds, o presidente Jair Bolsonaro agora resolveu eliminar tamb\u00e9m a exig\u00eancia legal da divulga\u00e7\u00e3o de editais de concursos, licita\u00e7\u00f5es e leil\u00f5es p\u00fablicos em jornais di\u00e1rios. Bolsonaro j\u00e1 havia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32],"tags":[],"class_list":{"0":"post-19207","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/09\/bolss.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19207"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=19207"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19207\/revisions"}],"predecessor-version":[{"id":19209,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19207\/revisions\/19209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/19208"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=19207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=19207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=19207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}