{"id":18949,"date":"2019-09-04T14:12:09","date_gmt":"2019-09-04T17:12:09","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=18949"},"modified":"2019-09-04T14:12:10","modified_gmt":"2019-09-04T17:12:10","slug":"motorista-se-perde-e-despenca-por-50-metros-barranco-abaixo","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/09\/04\/motorista-se-perde-e-despenca-por-50-metros-barranco-abaixo\/","title":{"rendered":"Motorista se perde e despenca por 50 metros barranco abaixo"},"content":{"rendered":"\n<p>Um poss\u00edvel erro na dire\u00e7\u00e3o pode ter sido a causa de um acidente nesta manh\u00e3 de quarta- feira (4). Um motorista, que n\u00e3o teve o nome divulgado, caiu em um barranco com o ve\u00edculo Palio azul na Rua Luiz Leduc, no bairro\u00a0<strong>Vista Alegre<\/strong>, em Curitiba.<\/p>\n\n\n\n<p>\u201cO rapaz veio aqui pegar algumas ferramentas e se perdeu. O carro capotou algumas vezes ao cair do barranco. Acredito que ele tenha ca\u00eddo por uns 50 metros. Ele teve sorte que a \u00e1rvore segurou o carro. Foi um barulho muito forte\u201d, relatou M\u00e1rcio Urias, vizinho da obra em que a v\u00edtima do acidente estava trabalhando.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.tribunapr.com.br\/wp-content\/uploads\/sites\/1\/2019\/09\/acidente-pilarzinho2-1110x685.jpg?a86372\" alt=\"Foto: Gerson Klaina\/Tribuna do Paran\u00e1\" class=\"wp-image-3019785\"\/><\/figure>\n\n\n\n<p>Foto: Gerson Klaina\/Tribuna do Paran\u00e1<\/p>\n\n\n\n<p>Mesmo ferido e com escoria\u00e7\u00f5es na cabe\u00e7a, o motorista subiu o barranco e chamou a irm\u00e3 que entrou em contato com o Corpo de Bombeiros.<\/p>\n\n\n\n<p>O Siate esteve no local e prestou os primeiros atendimentos. A v\u00edtima foi atendida e j\u00e1 liberada.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.tribunapr.com.br\/wp-content\/uploads\/sites\/1\/2019\/09\/acidente-pilarzinho-1110x685.jpg?a86372\" alt=\"Foto: Gerson Klaina\/Tribuna do Paran\u00e1\" class=\"wp-image-3019784\"\/><\/figure>\n\n\n\n<p>Tribuna do Paran\u00e1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um poss\u00edvel erro na dire\u00e7\u00e3o pode ter sido a causa de um acidente nesta manh\u00e3 de quarta- feira (4). Um motorista, que n\u00e3o teve o nome divulgado, caiu em um barranco com o ve\u00edculo Palio azul na Rua Luiz Leduc, no bairro\u00a0Vista Alegre, em Curitiba. \u201cO rapaz veio aqui pegar algumas ferramentas e se perdeu. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[52],"tags":[],"class_list":{"0":"post-18949","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-acidentes"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/09\/6250.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18949"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18949"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18949\/revisions"}],"predecessor-version":[{"id":18951,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18949\/revisions\/18951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/18950"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}