{"id":18943,"date":"2019-09-04T14:08:01","date_gmt":"2019-09-04T17:08:01","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=18943"},"modified":"2019-09-04T14:08:03","modified_gmt":"2019-09-04T17:08:03","slug":"as-brasileiras-atraidas-pelo-k-pop-e-forcadas-a-se-prostituir-na-coreia-do-sul","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/09\/04\/as-brasileiras-atraidas-pelo-k-pop-e-forcadas-a-se-prostituir-na-coreia-do-sul\/","title":{"rendered":"As brasileiras atra\u00eddas pelo K-pop e for\u00e7adas a se prostituir na Coreia do Sul"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">A pol\u00edcia da Coreia do Sul prendeu cinco homens acusados de for\u00e7ar pelo menos sete mulheres brasileiras a se prostitu\u00edrem.<\/h4>\n\n\n\n<p>Elas viajaram ao pa\u00eds ap\u00f3s terem sido enganadas com a promessa de uma carreira art\u00edstica no K-pop, mas foram v\u00edtimas de explora\u00e7\u00e3o sexual no pa\u00eds.<\/p>\n\n\n\n<p>No dia 17 de agosto, a Embaixada do Brasil recebeu um pedido de ajuda de uma das v\u00edtimas e entrou em contato com a pol\u00edcia coreana, &#8220;que prontamente iniciou investiga\u00e7\u00e3o sobre o caso&#8221;, segundo o Itamaraty.<\/p>\n\n\n\n<p>Ap\u00f3s o resgate, a previs\u00e3o \u00e9 que as v\u00edtimas retornem ao Brasil.<\/p>\n\n\n\n<p>&#8220;Como resultado da atua\u00e7\u00e3o policial, foram resgatadas sete brasileiras e detidos cidad\u00e3os coreanos suspeitos de envolvimento no esquema de explora\u00e7\u00e3o. As v\u00edtimas foram encaminhadas pela pol\u00edcia coreana a centro de prote\u00e7\u00e3o e apoio a mulheres estrangeiras, de onde dever\u00e3o retornar em seguran\u00e7a para o Brasil&#8221;, informou o Itamaraty.<\/p>\n\n\n\n<p>A assessoria de imprensa do Itamaraty n\u00e3o deu mais detalhes sobre o caso por envolver &#8220;aspectos relacionados \u00e0 privacidade individual dos assistidos&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que dizem as autoridades na Coreia<\/h2>\n\n\n\n<p>A BBC News Korean entrou em contato com a pol\u00edcia e representantes do governo local, que informaram que as v\u00edtimas brasileiras t\u00eam por volta de 20 a 30 anos e que foram resgatadas em dois locais diferentes. As autoridades coreanas elogiaram o suporte prestado pela Embaixada do Brasil \u00e0s v\u00edtimas.<\/p>\n\n\n\n<p>A reportagem tamb\u00e9m apurou que a pol\u00edcia coreana est\u00e1 investigando se houve outros casos semelhantes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/845D\/production\/_102958833_k8.jpg\" alt=\"Objetos com rostos de \u00eddolos K-pop\"\/><figcaption>Image captionObjetos com rostos de \u00eddolos K-pop, g\u00eanero musical originado na Coreia do Sul<\/figcaption><\/figure>\n\n\n\n<p>As v\u00edtimas brasileiras foram atra\u00eddas para a Coreia do Sul com promessas de que poderiam se tornar artistas ou dan\u00e7arinas de K-pop &#8211; g\u00eanero musical originado na Coreia do Sul e com popularidade crescente no Brasil.<\/p>\n\n\n\n<p>Segundo o site The Korea Times, os homens entraram em contato com as v\u00edtimas pelas redes sociais no in\u00edcio de julho e prometeram ajud\u00e1-las a se tornarem artistas ou modelos. Eles chegaram a oferecer as passagens de avi\u00e3o de ida e volta.<\/p>\n\n\n\n<p>Quando elas chegaram \u00e0 Coreia, em meados de julho, no entanto, os homens confiscaram os passaportes delas e cancelaram os voos de volta ao Brasil. Eles as confinaram em alojamentos nas cidades de Goyang e Paju, na prov\u00edncia de Gyeonggi, e depois venderam as mulheres para casas de prostitui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Elas foram amea\u00e7adas, segundo o site, com o argumento de que teriam de trabalhar at\u00e9 pagar o custo da viagem para a Coreia e ouviram que seriam punidas por prostitui\u00e7\u00e3o se procurassem a pol\u00edcia.<\/p>\n\n\n\n<p>A Embaixada da Coreia do Sul em Bras\u00edlia informou \u00e0 reportagem que n\u00e3o tem registro das brasileiras que viajaram \u00e0 Coreia do Sul, j\u00e1 que n\u00e3o \u00e9 necess\u00e1rio emitir visto para brasileiros que v\u00e3o passar at\u00e9 90 dias, em viagem de turismo, no pa\u00eds.<\/p>\n\n\n\n<p>O Itamaraty informou que &#8220;a Embaixada do Brasil em Seul tem prestado toda a assist\u00eancia poss\u00edvel \u00e0s cidad\u00e3s brasileiras v\u00edtimas de recente caso de explora\u00e7\u00e3o sexual na Coreia do Sul&#8221; e que continuar\u00e1 acompanhando o caso &#8220;com toda a aten\u00e7\u00e3o&#8221;.<\/p>\n\n\n\n<p>BBC<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00edcia da Coreia do Sul prendeu cinco homens acusados de for\u00e7ar pelo menos sete mulheres brasileiras a se prostitu\u00edrem. Elas viajaram ao pa\u00eds ap\u00f3s terem sido enganadas com a promessa de uma carreira art\u00edstica no K-pop, mas foram v\u00edtimas de explora\u00e7\u00e3o sexual no pa\u00eds. No dia 17 de agosto, a Embaixada do Brasil recebeu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[55],"tags":[],"class_list":{"0":"post-18943","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-curiosidades"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/09\/ciciu.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18943"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18943"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18943\/revisions"}],"predecessor-version":[{"id":18945,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18943\/revisions\/18945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/18944"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}