{"id":17883,"date":"2019-08-22T12:36:11","date_gmt":"2019-08-22T15:36:11","guid":{"rendered":"https:\/\/www.paranapraia.com.br\/?p=17883"},"modified":"2019-08-22T12:36:15","modified_gmt":"2019-08-22T15:36:15","slug":"prefeitura-de-pontal-do-parana-aumenta-valor-de-auxilio-alimentacao-aos-servidores-publicos","status":"publish","type":"post","link":"https:\/\/www.paranapraia.com.br\/index.php\/2019\/08\/22\/prefeitura-de-pontal-do-parana-aumenta-valor-de-auxilio-alimentacao-aos-servidores-publicos\/","title":{"rendered":"Prefeitura de Pontal do Paran\u00e1 aumenta valor de aux\u00edlio-alimenta\u00e7\u00e3o aos servidores p\u00fablicos"},"content":{"rendered":"\n<p>A prefeitura de Pontal do Paran\u00e1 vai conceder no m\u00eas de agosto um reajuste de 50% no aux\u00edlio-alimenta\u00e7\u00e3o dos servidores p\u00fablicos, desde o in\u00edcio da administra\u00e7\u00e3o o reajuste foi de 150%.<br>&nbsp;<\/p>\n\n\n\n<p>Em 2017 quando o prefeito Marcos Fioravante assumiu a gest\u00e3o do munic\u00edpio o aux\u00edlio era no valor de R$ 135,57 reais, j\u00e1 em 2018 com um reajuste de 100% passou para R$ 271,14 e agora em 2019 mais um reajuste de 50%, que garante o benef\u00edcio no valor de R$ 393,72 reais, o aumento \u00e9 de acordo com a Lei Municipal n\u00ba 1959\/2019.<br>&nbsp;<\/p>\n\n\n\n<p>No m\u00eas de dezembro, excepcionalmente, para gratificar ainda mais os servidores pela dedica\u00e7\u00e3o, o benef\u00edcio ser\u00e1 no valor de R$ 492,15 reais, o valor do aux\u00edlio \u00e9 baseado na UFM \u2013 Unidade Fiscal do Munic\u00edpio, que passou de 1,5 UFM em 2017 para 4 UFM em 2019.<br>&nbsp;<\/p>\n\n\n\n<p>O Prefeito Marcos Fioravante (Casquinha) considera que o vale-alimenta\u00e7\u00e3o \u00e9 uma forma de demonstrar a import\u00e2ncia e o reconhecimento pelo trabalho desenvolvido pelos servidores municipais, o que se reflete no atendimento das necessidades e anseios da popula\u00e7\u00e3o. Ele explicou que o aux\u00edlio significar\u00e1 um aumento nas possibilidades de alimenta\u00e7\u00e3o e da qualidade de vida da fam\u00edlia do servidor.<br>&nbsp;<\/p>\n\n\n\n<p>&nbsp;\u201cEu me sinto muito feliz em poder ajudar nossos servidores com esse aumento, imagine que quando entramos aqui o vale era no valor de R$ 135 reais e agora estamos em R$ 393 reais, um aumento de 150% que ajuda muito as fam\u00edlias, \u00e9 um valor que j\u00e1 se pode fazer uma boa compra para a fam\u00edlia e ajudar no or\u00e7amento. \u00c9 uma satisfa\u00e7\u00e3o poder proporcionar o aumento deste benef\u00edcio para o servidor que deve ter seu trabalho e esfor\u00e7o reconhecidos pela Administra\u00e7\u00e3o Municipal\u201d, completou o prefeito.<br>&nbsp;<\/p>\n\n\n\n<p>A auxiliar de Servi\u00e7os Gerais Raquel Rocha, disse que antigamente o aux\u00edlio-alimenta\u00e7\u00e3o era motivo de ironias porque o valor era muito baixo e todos criticavam.<br>&nbsp;<\/p>\n\n\n\n<p>\u201cCom certeza o aumento que o prefeito Casquinha deu nos ajuda muito, porque podemos fazer uma compra para o m\u00eas inteiro praticamente e isso \u00e9 muito importante para quem tem uma fam\u00edlia grande, esse aumento vai ajudar todos os servidores e suas fam\u00edlias\u201d, disse Raquel.<br>&nbsp;<\/p>\n\n\n\n<p>A secretaria de Administra\u00e7\u00e3o, Lilian Gabardo, falou ainda que anualmente o aux\u00edlio sofre reajuste em fun\u00e7\u00e3o da altera\u00e7\u00e3o da UFM. \u201cCom certeza o aumento promover\u00e1\u00a0um impacto nas finan\u00e7as dos servidores e tamb\u00e9m movimentar\u00e1\u00a0o com\u00e9rcio local em nossa cidade\u201d, finalizou Lilian.<\/p>\n\n\n\n<p>Prefeitura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura de Pontal do Paran\u00e1 vai conceder no m\u00eas de agosto um reajuste de 50% no aux\u00edlio-alimenta\u00e7\u00e3o dos servidores p\u00fablicos, desde o in\u00edcio da administra\u00e7\u00e3o o reajuste foi de 150%.&nbsp; Em 2017 quando o prefeito Marcos Fioravante assumiu a gest\u00e3o do munic\u00edpio o aux\u00edlio era no valor de R$ 135,57 reais, j\u00e1 em 2018 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-17883","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destaques"},"jetpack_featured_media_url":"https:\/\/www.paranapraia.com.br\/wp-content\/uploads\/2019\/08\/GCDDDDD.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17883"}],"collection":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17883"}],"version-history":[{"count":1,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17883\/revisions"}],"predecessor-version":[{"id":17885,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17883\/revisions\/17885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media\/17884"}],"wp:attachment":[{"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paranapraia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}